{"id":97710,"date":"2025-08-13T10:03:23","date_gmt":"2025-08-13T14:03:23","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=97710"},"modified":"2025-08-13T10:03:23","modified_gmt":"2025-08-13T14:03:23","slug":"soyez-pret-pour-linscription","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2025\/08\/13\/soyez-pret-pour-linscription\/","title":{"rendered":"Soyez pr\u00eat pour l\u2019inscription"},"content":{"rendered":"<p>L\u2019inscription \u00e0 l\u2019\u00c9valuation des connaissances fondamentales (\u00c9CF) de f\u00e9vrier 2026 d\u00e9butera le 16 septembre 2025 \u00e0 10 h HE.<\/p>\n<p>Pour vous aider \u00e0 vous pr\u00e9parer avant le jour de l\u2019inscription, nous avons cr\u00e9\u00e9 une courte vid\u00e9o disponible dans notre <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/videotheque\/\" target=\"_blank\" rel=\"noopener\">Vid\u00e9oth\u00e8que<\/a>.<\/p>\n<p>Que vous soyez un nouveau candidat ou que vous poursuiviez votre processus d\u2019obtention du permis, <em>Soyez pr\u00eat pour l\u2019inscription<\/em> vous explique comment vous pr\u00e9parer \u00e0 l\u2019inscription, \u00e0 quoi vous attendre et comment \u00e9viter les erreurs courantes.<\/p>\n<p>Nous vous invitons \u00e9galement \u00e0 explorer notre page <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/ressources\/ressources-dexamens\/\" target=\"_blank\" rel=\"noopener\">Ressources d\u2019examens<\/a>, o\u00f9 vous trouverez la vid\u00e9o d\u2019o<em>rientation sur l\u2019examen \u00e9lectronique pour \u00c9CF et \u00c9JC<\/em> qui donne un aper\u00e7u de la plateforme d\u2019examen et vous aide \u00e0 comprendre \u00e0 quoi vous attendre le jour de l\u2019examen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019inscription \u00e0 l\u2019\u00c9valuation des connaissances fondamentales (\u00c9CF) de f\u00e9vrier 2026 d\u00e9butera le 16 septembre 2025 \u00e0 10 h HE. Pour vous aider \u00e0 vous pr\u00e9parer avant le jour de l\u2019inscription,&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-97710","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=97710"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97710\/revisions"}],"predecessor-version":[{"id":97711,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97710\/revisions\/97711"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=97710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=97710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=97710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}