{"id":97698,"date":"2025-08-08T08:56:22","date_gmt":"2025-08-08T12:56:22","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=97698"},"modified":"2025-08-08T08:56:22","modified_gmt":"2025-08-08T12:56:22","slug":"notre-plan-strategique-en-action","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2025\/08\/08\/notre-plan-strategique-en-action\/","title":{"rendered":"Notre plan strat\u00e9gique en action"},"content":{"rendered":"<p>Avec le lancement de notre Plan strat\u00e9gique 2025-2029, une feuille de route tourn\u00e9e vers l&rsquo;avenir et articul\u00e9e autour de quatre priorit\u00e9s cl\u00e9s, nous r\u00e9affirmons notre engagement \u00e0 contribuer \u00e0 la sant\u00e9 bucco-dentaire des Canadiens gr\u00e2ce \u00e0 une \u00e9valuation \u00e9quitable, valide et fiable des comp\u00e9tences.<\/p>\n<p>Au cours des derniers mois, nous avons mis en place de nouveaux outils afin de fournir aux personnes int\u00e9ress\u00e9es des renseignements clairs et accessibles sur les examens et les processus du BNED.<\/p>\n<p>Ce travail t\u00e9moigne de notre engagement continu \u00e0 veiller \u00e0 ce que toutes nos parties prenantes soient bien inform\u00e9s des processus, des politiques et des pratiques en constante \u00e9volution du BNED.<\/p>\n<p><strong>Des ressources adapt\u00e9es pour vous aider dans votre cheminement vers la certification<\/strong><\/p>\n<p>Nous nous engageons \u00e0 \u00e9laborer des ressources qui favorisent une meilleure compr\u00e9hension des processus du BNED en offrant du mat\u00e9riel adapt\u00e9 \u00e0 divers styles et pr\u00e9f\u00e9rences d&rsquo;apprentissage. Pour appuyer cet objectif, nous avons:<\/p>\n<ul>\n<li>Tenue notre premi\u00e8re s\u00e9ance d&rsquo;information sur l&rsquo;\u00c9valuation du jugement clinique (\u00c9JC).<\/li>\n<li>Produit une s\u00e9rie de courtes vid\u00e9os informatives qui expliquent les \u00e9tapes cl\u00e9s des processus du BNED.<\/li>\n<li>Poursuivi notre collaboration avec d&rsquo;autres organisations afin de fournir des renseignements exacts et opportuns aux personnes qui souhaitent obtenir un permis d&rsquo;exercice ou une certification.<\/li>\n<\/ul>\n<p>Cette initiative n&rsquo;est qu&rsquo;une partie de notre priorit\u00e9 plus large qui consiste \u00e0 reconna\u00eetre les besoins diversifi\u00e9s de nos candidats et \u00e0 \u00e9laborer des processus pour les aider \u00e0 obtenir leur certification.<\/p>\n<p>Pour en savoir plus sur nos priorit\u00e9s strat\u00e9giques pour 2025-2029, consultez notre page <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/a-propos\/\" target=\"_blank\" rel=\"noopener\">\u00c0 propos du BNED<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec le lancement de notre Plan strat\u00e9gique 2025-2029, une feuille de route tourn\u00e9e vers l&rsquo;avenir et articul\u00e9e autour de quatre priorit\u00e9s cl\u00e9s, nous r\u00e9affirmons notre engagement \u00e0 contribuer \u00e0 la&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-97698","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=97698"}],"version-history":[{"count":2,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97698\/revisions"}],"predecessor-version":[{"id":97700,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97698\/revisions\/97700"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=97698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=97698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=97698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}