{"id":97044,"date":"2025-06-06T12:24:16","date_gmt":"2025-06-06T16:24:16","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=97044"},"modified":"2025-06-06T12:25:59","modified_gmt":"2025-06-06T16:25:59","slug":"ouverture-des-inscriptions-a-lecj-de-novembre","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2025\/06\/06\/ouverture-des-inscriptions-a-lecj-de-novembre\/","title":{"rendered":"Ouverture des inscriptions \u00e0 l\u2019\u00c9CJ de novembre"},"content":{"rendered":"<p>L&rsquo;inscription \u00e0 l\u2019\u00c9valuation du jugement clinique (\u00c9JC) qui aura lieu le 25 novembre 2025 ouvrira le 10 juin 2025 \u00e0 10 h HE. Pour vous inscrire, <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/connectez-vous-a-votre-profil-en-ligne\/\" target=\"_blank\" rel=\"noopener\">connectez-vous \u00e0 votre compte NDEBConnect<\/a>.<\/p>\n<p>L&rsquo;\u00c9JC est la deuxi\u00e8me \u00e9tape du Processus d&rsquo;\u00e9quivalence. Il \u00e9value votre capacit\u00e9 \u00e0 formuler un diagnostic et \u00e0 prendre des d\u00e9cisions dans un contexte clinique. Cet examen \u00e9lectronique est administr\u00e9 dans les centres de test Prometric de plusieurs villes canadiennes, en Australie et Nouvelle-Z\u00e9lande.<\/p>\n<p>Une fois inscrit, nous vous encourageons \u00e0 regarder la <em>Vid\u00e9o d&rsquo;orientation pour la version \u00e9lectronique de l\u2019\u00c9CF et l\u2019\u00c9JC<\/em> nos <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/ressources\/ressources-dexamens\/\" target=\"_blank\" rel=\"noopener\">Ressources d\u2019exam<\/a> afin de vous familiariser avec la plateforme avant le jour de l&rsquo;examen. \u00c0 la fin de la vid\u00e9o, vous aurez l&rsquo;occasion d&rsquo;essayer la plateforme \u00e9lectronique.<\/p>\n<p>De plus, nous vous recommandons de consulter le <em>Protocole \u00c9JC<\/em> et le <em>Canevas des questions et r\u00e9ponses de l\u2019\u00c9JC<\/em> qui fourniront des informations essentielles sur le format de l&rsquo;examen et la notation.<\/p>\n<p>Vous pouvez \u00e9galement acc\u00e9der \u00e0 la s\u00e9ance d&rsquo;information sur l&rsquo;\u00c9JC\u00a0dans la <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/videotheque\/\" target=\"_blank\" rel=\"noopener\">vid\u00e9oth\u00e8que<\/a>. Cette s\u00e9ance couvre le format de l\u2019examen, les crit\u00e8res d\u2019\u00e9valuation, les dates limites importantes ainsi que des conseils pratiques pour le jour de l\u2019examen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;inscription \u00e0 l\u2019\u00c9valuation du jugement clinique (\u00c9JC) qui aura lieu le 25 novembre 2025 ouvrira le 10 juin 2025 \u00e0 10 h HE. Pour vous inscrire, connectez-vous \u00e0 votre compte&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-97044","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=97044"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97044\/revisions"}],"predecessor-version":[{"id":97045,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/97044\/revisions\/97045"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=97044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=97044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=97044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}