{"id":96852,"date":"2025-05-27T10:07:01","date_gmt":"2025-05-27T14:07:01","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=96852"},"modified":"2025-05-27T14:27:26","modified_gmt":"2025-05-27T18:27:26","slug":"changements-inscription-a-ledncc","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2025\/05\/27\/changements-inscription-a-ledncc\/","title":{"rendered":"Changements : inscription \u00e0 l\u2019EDNCC"},"content":{"rendered":"<p>Au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e, nous avons pris en compte les commentaires et suggestions de divers groupes sur la mani\u00e8re d\u2019am\u00e9liorer l\u2019inscription \u00e0 l\u2019EDNCC et de r\u00e9duire la dur\u00e9e du Processus d\u2019\u00e9quivalence.<\/p>\n<p>Plus t\u00f4t cette ann\u00e9e, nous avons commenc\u00e9 \u00e0 recueillir des preuves de citoyennet\u00e9 canadienne ou de r\u00e9sidence permanente aupr\u00e8s des candidats. Ces informations ont \u00e9t\u00e9 collect\u00e9es afin d\u2019informer les changements d\u2019inscription pour les examens du BNED.<\/p>\n<p>Les dipl\u00f4m\u00e9s de programmes dentaires non accr\u00e9dit\u00e9s qui se sont \u00e9tablis au Canada ne peuvent pas travailler comme dentistes tant qu\u2019ils n\u2019ont pas termin\u00e9 soit un programme de perfectionnement de dipl\u00f4me, soit le Processus d\u2019\u00e9quivalence du BNED.<\/p>\n<p>Afin d\u2019aider ces dentistes \u00e0 commencer \u00e0 pratiquer plus rapidement, nous allons mettre en \u0153uvre notre plan visant \u00e0 donner la priorit\u00e9 aux citoyens canadiens et aux r\u00e9sidents permanents pour l\u2019inscription \u00e0 l\u2019EDNCC.<\/p>\n<p>Ce changement prendra effet le 1er juillet 2025.\u00a0 \u00c0 ce moment-l\u00e0, l\u2019inscription \u00e0 l\u2019EDNCC se d\u00e9roulera en trois \u00e9tapes :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-96882 alignright\" src=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/wp-content\/uploads\/2025\/05\/2-1-300x288.png\" alt=\"\" width=\"336\" height=\"322\" srcset=\"https:\/\/ndeb-bned.ca\/wp-content\/uploads\/2025\/05\/2-1-300x288.png 300w, https:\/\/ndeb-bned.ca\/wp-content\/uploads\/2025\/05\/2-1.png 750w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/p>\n<ol>\n<li>Candidats \u00e0 l\u2019EDNCC qui s\u2019inscrivent pour la premi\u00e8re fois et ont obtenu un r\u00e9sultat satisfaisant au plus r\u00e9cent ACJ.<\/li>\n<li>Candidats \u00e0 l\u2019EDNCC ayant fourni une preuve de citoyennet\u00e9 canadienne ou de r\u00e9sidence permanente.<\/li>\n<li>Tous les candidats ayant l\u2019\u00e9ligibilit\u00e9 \u00e0 l\u2019EDNCC.<\/li>\n<\/ol>\n<p>Nous croyons que ce changement soutient l\u2019engagement des candidats qui ont choisi le Canada comme lieu de r\u00e9sidence et leur permettra de commencer \u00e0 pratiquer plus rapidement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e, nous avons pris en compte les commentaires et suggestions de divers groupes sur la mani\u00e8re d\u2019am\u00e9liorer l\u2019inscription \u00e0 l\u2019EDNCC et de r\u00e9duire la dur\u00e9e du&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-96852","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/96852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=96852"}],"version-history":[{"count":11,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/96852\/revisions"}],"predecessor-version":[{"id":96920,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/96852\/revisions\/96920"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=96852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=96852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=96852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}