{"id":96648,"date":"2025-05-09T14:00:06","date_gmt":"2025-05-09T18:00:06","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=96648"},"modified":"2025-05-09T14:07:01","modified_gmt":"2025-05-09T18:07:01","slug":"interruption-potentielle-des-services-de-postes-canada","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2025\/05\/09\/interruption-potentielle-des-services-de-postes-canada\/","title":{"rendered":"Interruption potentielle des services de Postes Canada"},"content":{"rendered":"<p>Il est possible que les services de Postes Canada soient interrompus en mai 2025. Une interruption des services aura une incidence minimale sur les services du BNED, car la plupart d&rsquo;entre eux sont offerts par voie \u00e9lectronique. Toutefois, la livraison des certificats du BNED d\u00e9pend du syst\u00e8me postal. En cas d&rsquo;interruption des services, la BNED s&rsquo;efforcera de trouver d&rsquo;autres moyens d&rsquo;offrir ce service.<\/p>\n<p>Nous encourageons les candidats \u00e0 se tenir inform\u00e9s des derni\u00e8res nouvelles concernant la perturbation potentielle des services de Postes Canada et \u00e0 envisager d&rsquo;envoyer les documents requis \u00e0 notre bureau par messagerie afin d&rsquo;\u00e9viter tout retard.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est possible que les services de Postes Canada soient interrompus en mai 2025. Une interruption des services aura une incidence minimale sur les services du BNED, car la plupart&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-96648","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/96648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=96648"}],"version-history":[{"count":2,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/96648\/revisions"}],"predecessor-version":[{"id":96650,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/96648\/revisions\/96650"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=96648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=96648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=96648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}