{"id":94885,"date":"2024-09-05T09:06:02","date_gmt":"2024-09-05T13:06:02","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=94885"},"modified":"2024-09-05T09:06:02","modified_gmt":"2024-09-05T13:06:02","slug":"saviez-vous-quil-y-a-plus-dune-facon-dobtenir-la-certification-du-bned","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2024\/09\/05\/saviez-vous-quil-y-a-plus-dune-facon-dobtenir-la-certification-du-bned\/","title":{"rendered":"Saviez-vous qu&rsquo;il y a plus d&rsquo;une fa\u00e7on d&rsquo;obtenir la certification du BNED ?"},"content":{"rendered":"<p>En tant que dentiste form\u00e9 dans un programme dentaire international non-agr\u00e9\u00e9, il existe deux voies pour obtenir la certification du BNED. Lorsqu&rsquo;il s&rsquo;agit de choisir la voie qui vous convient le mieux, il y a de nombreux \u00e9l\u00e9ments \u00e0 prendre en compte, dont le co\u00fbt.<\/p>\n<p>La premi\u00e8re voie \u00e0 envisager est celle d&rsquo;un programme agr\u00e9\u00e9 de qualification ou d\u2019obtention de dipl\u00f4me offert par les facult\u00e9s de m\u00e9decine dentaire au Canada et aux \u00c9tats-Unis. Ces programmes sont sp\u00e9cifiquement con\u00e7us pour combler les lacunes des personnes form\u00e9es dans des programmes dentaires non-agr\u00e9\u00e9s, en les aidant \u00e0 se familiariser avec les pratiques dentaires canadiennes. Apr\u00e8s avoir termin\u00e9 avec succ\u00e8s l&rsquo;un de ces programmes, une personne peut se pr\u00e9senter \u00e0 l&rsquo;examen de certification du BNED. Chaque facult\u00e9 fixe ses propres frais de scolarit\u00e9 et co\u00fbts associ\u00e9s, les frais de ces programmes peuvent donc varier consid\u00e9rablement en fonction de l&rsquo;\u00e9tablissement. Notre page web des <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/processus-dequivalence\/programmes-de-qualification-ou-dobtention-de-diplome\/\" target=\"_blank\" rel=\"noopener\">Programmes de qualification ou d&rsquo;obtention de dipl\u00f4me<\/a> fournit une liste de contacts des facult\u00e9s dentaires canadiennes. Nous vous recommandons de les contacter directement pour en savoir plus sur les frais de leurs programmes.<\/p>\n<p>Une autre voie d&rsquo;acc\u00e8s \u00e0 la certification consiste \u00e0 r\u00e9ussir le Processus d&rsquo;\u00e9quivalence du NDEB, qui comprend trois examens. Chaque examen du Processus d&rsquo;\u00e9quivalence est soumis \u00e0 des frais fixes. Les frais sont revus chaque ann\u00e9e et peuvent \u00eatre modifi\u00e9s. En incluant les frais de candidature, le co\u00fbt total du Processus d&rsquo;\u00e9quivalence est de 12 600 dollars canadiens. Ce montant augmentera si une personne doit passer un examen plus d&rsquo;une fois. Notre page web <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/considerer-le-canada\/\" target=\"_blank\" rel=\"noopener\">Envisagez-vous le Canada?<\/a> fournit des informations sur les co\u00fbts associ\u00e9s aux examens du BNED et un exemple de calendrier d&rsquo;un candidat au Processus d&rsquo;\u00e9quivalence qui doit repasser des examens.<\/p>\n<p>Lorsque vous envisagez de suivre le Processus d&rsquo;\u00e9quivalence, il est bon de prendre en compte les d\u00e9penses autres que le co\u00fbt des examens, telles que les frais de voyage et d&rsquo;h\u00e9bergement. Les examens du BNED se d\u00e9roulent principalement au Canada. Les candidats doivent \u00eatre pr\u00eats \u00e0 voyager de leur pays de r\u00e9sidence jusqu&rsquo;au lieu de l&rsquo;examen, en particulier pour l\u2019EDNCC, qui se d\u00e9roule au centre de test de l\u2019EDNCC \u00e0 Ottawa.<\/p>\n<p>Lors de la soumission de votre demande pour le Processus d&rsquo;\u00e9quivalence, vous devrez pr\u00e9senter des documents notari\u00e9s et des traductions originales pour les documents r\u00e9dig\u00e9s dans des langues autres que l&rsquo;anglais ou le fran\u00e7ais. Notez que ces documents sont n\u00e9cessaires afin de v\u00e9rifier vos qualifications et qu&rsquo;ils peuvent repr\u00e9senter un co\u00fbt suppl\u00e9mentaire.<\/p>\n<p>Il existe de nombreux programmes et cours pour aider les personnes \u00e0 se pr\u00e9parer aux examens du BNED. Bien que les co\u00fbts des cours de pr\u00e9paration aux examens soient souvent consid\u00e9r\u00e9s comme faisant partie du Processus d&rsquo;\u00e9quivalence, ils ne sont pas offerts ni approuv\u00e9s par le BNED et ne sont pas requis pour participer aux examens. Avant d&rsquo;envisager le Processus d&rsquo;\u00e9quivalence, il est bon de prendre en compte les co\u00fbts suppl\u00e9mentaires associ\u00e9s \u00e0 l&rsquo;inscription \u00e0 de tels programmes.<\/p>\n<p>Quelle que soit la voie choisie, des ressources sont disponibles sur notre site web pour vous aider.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En tant que dentiste form\u00e9 dans un programme dentaire international non-agr\u00e9\u00e9, il existe deux voies pour obtenir la certification du BNED. Lorsqu&rsquo;il s&rsquo;agit de choisir la voie qui vous convient&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-94885","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/94885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=94885"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/94885\/revisions"}],"predecessor-version":[{"id":94887,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/94885\/revisions\/94887"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=94885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=94885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=94885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}