{"id":94447,"date":"2024-06-05T11:32:41","date_gmt":"2024-06-05T15:32:41","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=94447"},"modified":"2024-06-05T11:32:41","modified_gmt":"2024-06-05T15:32:41","slug":"a-venir-inscription-a-lejc-de-novembre-2024","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2024\/06\/05\/a-venir-inscription-a-lejc-de-novembre-2024\/","title":{"rendered":"\u00c0 venir : Inscription \u00e0 l&rsquo;\u00c9JC de novembre 2024"},"content":{"rendered":"<p>L&rsquo;inscription \u00e0 l&rsquo;\u00c9JC du 26 novembre 2024 ouvre le 12 juin 2024 \u00e0 10 heures (heure de l&rsquo;Est).<\/p>\n<p>L&rsquo;ACJ est un examen \u00e9lectronique offert dans un double format dans les centres d&rsquo;examen Prometric au Canada, en Australie et en Nouvelle-Z\u00e9lande, ainsi qu\u2019au centre d\u2019examen d\u2019Ottawa.<\/p>\n<p>Il existe des diff\u00e9rences importantes entre l&rsquo;administration de l&rsquo;examen par Prometric et par le centre d&rsquo;examen d&rsquo;Ottawa:<\/p>\n<ul>\n<li>Les candidats inscrits aux centres d&rsquo;examen Prometric recevront l\u2019horaire et le lieu de l&rsquo;examen apr\u00e8s avoir pris rendez-vous avec Prometric. L&rsquo;horaire et le lieu de l&rsquo;examen pour les personnes inscrites au centre d&rsquo;examen d&rsquo;Ottawa sont disponibles sur leur profil NDEBConnect.<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li>Pendant l&rsquo;examen, les candidats qui passent l&rsquo;examen avec Prometric auront une pause de 30 minutes, tandis que ceux qui se trouvent au centre d&rsquo;examen d&rsquo;Ottawa b\u00e9n\u00e9ficieront d&rsquo;une pause plus longue d&rsquo;une heure pour permettre la r\u00e9installation de la salle d&rsquo;examen et l&rsquo;inscription des candidats.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Une fois inscrits, les candidats doivent consulter la note d&rsquo;information disponible dans leur profil en ligne. Dans ce document, les candidats trouveront des informations sp\u00e9cifiques relatives \u00e0 leur lieu d&rsquo;examen.<\/p>\n<p>Pour vous inscrire, <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/connectez-vous-a-votre-profil-en-ligne\/\">connectez-vous \u00e0 votre compte NDEBConnect<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;inscription \u00e0 l&rsquo;\u00c9JC du 26 novembre 2024 ouvre le 12 juin 2024 \u00e0 10 heures (heure de l&rsquo;Est). L&rsquo;ACJ est un examen \u00e9lectronique offert dans un double format dans les&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-94447","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/94447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=94447"}],"version-history":[{"count":11,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/94447\/revisions"}],"predecessor-version":[{"id":94460,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/94447\/revisions\/94460"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=94447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=94447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=94447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}