{"id":92381,"date":"2023-11-20T12:54:09","date_gmt":"2023-11-20T17:54:09","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=92381"},"modified":"2023-11-20T12:54:09","modified_gmt":"2023-11-20T17:54:09","slug":"lejc-de-novembre-2023-arrive-bientot","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2023\/11\/20\/lejc-de-novembre-2023-arrive-bientot\/","title":{"rendered":"L&rsquo;\u00c9JC de novembre 2023 arrive bient\u00f4t"},"content":{"rendered":"<p>L\u2019\u00c9JC du 23 novembre approche \u00e0 grands pas.<\/p>\n<p>L&rsquo;\u00c9JC est une \u00e9valuation \u00e9lectronique compos\u00e9e de 120 \u00e0 150 questions \u00e0 choix multiples \u00e0 r\u00e9ponse unique ou \u00e0 r\u00e9ponses multiples.<\/p>\n<p>Les questions \u00e0 choix multiples comportant plus d&rsquo;une r\u00e9ponse correcte et un score maximum de 1.<\/p>\n<p>Votre score pour une question d\u00e9pend du fait que vous ayez choisi les bonnes r\u00e9ponses, certaines des bonnes r\u00e9ponses ou une mauvaise r\u00e9ponse. Pour obtenir des points pour une question, vous devez uniquement s\u00e9lectionner les bonnes r\u00e9ponses. M\u00eame si vous choisissez une seule r\u00e9ponse incorrecte, vous obtiendrez un score de z\u00e9ro.<\/p>\n<p>Pour vous pr\u00e9parer \u00e0 l\u2019examen, nous vous invitons \u00e0 consulter notre fiche d\u2019information sur les<em> Questions \u00e0 plusieurs r\u00e9ponses <\/em>et notre<em> Canvas de questions et r\u00e9ponses ACJ<\/em> sur notre page web <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/ressources\/comment-se-preparer\/\" target=\"_blank\" rel=\"noopener\">Comment se pr\u00e9parer<\/a>. Ces documents fournissent des d\u00e9tails sur le format et le contenu des questions de l&rsquo;examen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00c9JC du 23 novembre approche \u00e0 grands pas. L&rsquo;\u00c9JC est une \u00e9valuation \u00e9lectronique compos\u00e9e de 120 \u00e0 150 questions \u00e0 choix multiples \u00e0 r\u00e9ponse unique ou \u00e0 r\u00e9ponses multiples. Les&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-92381","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/92381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=92381"}],"version-history":[{"count":3,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/92381\/revisions"}],"predecessor-version":[{"id":92384,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/92381\/revisions\/92384"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=92381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=92381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=92381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}