{"id":40740,"date":"2022-05-26T14:03:40","date_gmt":"2022-05-26T18:03:40","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?p=40740"},"modified":"2022-05-31T15:40:51","modified_gmt":"2022-05-31T19:40:51","slug":"mise-a-jour-des-reglements-de-bned","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2022\/05\/26\/mise-a-jour-des-reglements-de-bned\/","title":{"rendered":"Mise \u00e0 jour des r\u00e8glements de BNED\u00ae"},"content":{"rendered":"<p><span data-contrast=\"auto\">\u00c0 partir du 1er juillet, les R\u00e8glements du BNED<sup>\u00ae<\/sup> r\u00e9vis\u00e9s entreront en vigueur. Cette mise \u00e0 jour comprend des changements concernant la reprise de l\u2019 EDNCC<sup>\u00ae<\/sup>. \u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">L\u2019 EDNCC<sup>\u00ae<\/sup> consiste en deux composantes, d\u2019Habilet\u00e9s cliniques et de Jugement situationnel, r\u00e9alis\u00e9es au cours de deux jours d\u2019examens cons\u00e9cutifs. La r\u00e9ussite de l\u2019 EDNCC<sup>\u00ae<\/sup> est requise pour compl\u00e9ter le Processus d&rsquo;\u00e9quivalence. \u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Comme stipul\u00e9 dans les r\u00e8glements r\u00e9vis\u00e9s, un candidat qui \u00e9choue soit la composante d\u2019Habilit\u00e9s cliniques ou la composante Jugement situationnel de l\u2019 EDNCC<sup>\u00ae<\/sup> ne doit reprendre que la composante \u00e9chou\u00e9e. Si les deux composantes sont \u00e9chou\u00e9es, le candidat doit reprendre l\u2019 EDNCC<sup>\u00ae<\/sup> au complet. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">L\u2019 EDNCC<sup>\u00ae<\/sup> peut \u00eatre repris autant de fois que n\u00e9cessaire dans les 60 mois qui suivent la date d&rsquo;introduction de l\u2019 EDNCC<sup>\u00ae<\/sup> ou la date de r\u00e9ussite de l&rsquo;\u00c9JC. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Les R\u00e8glements du BNED<sup>\u00ae<\/sup> r\u00e9vis\u00e9s seront disponibles sur le site Web du BNED \u00e0 la fin juin 2022. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 partir du 1er juillet, les R\u00e8glements du BNED\u00ae r\u00e9vis\u00e9s entreront en vigueur. Cette mise \u00e0 jour comprend des changements concernant la reprise de l\u2019 EDNCC\u00ae. \u00a0\u00a0 L\u2019 EDNCC\u00ae consiste&#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-40740","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/40740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=40740"}],"version-history":[{"count":5,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/40740\/revisions"}],"predecessor-version":[{"id":44043,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/40740\/revisions\/44043"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=40740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=40740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=40740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}