{"id":3547,"date":"2015-07-23T00:00:00","date_gmt":"2021-06-25T14:31:52","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/le-bned-embauche-un-conseiller-juridique-a-linterne-et-directeur-des-communications\/"},"modified":"2021-06-25T10:33:57","modified_gmt":"2021-06-25T14:33:57","slug":"le-bned-embauche-un-conseiller-juridique-a-linterne-et-directeur-des-communications","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2015\/07\/23\/le-bned-embauche-un-conseiller-juridique-a-linterne-et-directeur-des-communications\/","title":{"rendered":"Le BNED embauche un conseiller juridique \u00e0 l&rsquo;interne et directeur des Communications"},"content":{"rendered":"<p>Le Bureau national d&rsquo;examen dentaire du Canada (BNED) est heureux d&rsquo;annoncer que Steven Pink se joindra au BNED dans un double r\u00f4le de conseiller juridique \u00e0 l&rsquo;interne et directeur des Communications \u00e0 partir du 8 Septembre 2015. Monsieur Pink agira \u00e0 la fois comme avocat-conseil interne et expert en communication pour tous les probl\u00e8mes d\u2019aspect juridique et de communication du BNED.<\/p>\n<p>Les responsabilit\u00e9s de ce nouveau poste, comprennent l&rsquo;identification et la surveillance de tous les aspects juridiques, y compris le respect de la l\u00e9gislation applicable, de la supervision de litiges, les questions d&#8217;emploi, l&rsquo;analyse des risques, les questions de droits d&rsquo;auteur, du d\u00e9veloppement international et de contrats d&rsquo;intervenants. M. Pink repr\u00e9sentera le BNED aupr\u00e8s des intervenants nationaux et internationaux en mati\u00e8re juridique et de communication et agira comme porte-parole du BNED aupr\u00e8s des m\u00e9dias et autres demandeurs.<\/p>\n<p>M. Pink va \u00e9galement \u00e9laborer et diriger la mise en \u009cuvre, l&rsquo;\u00e9valuation et l&rsquo;am\u00e9lioration des plans et strat\u00e9gies de communication interne et externe. En tant que sp\u00e9cialiste des communications du BNED, M. Pink s&rsquo;assurera de la coh\u00e9rence, de la pr\u00e9cision et du professionnalisme des communications avec les intervenants internes et externes en ce qui a trait au mandat du BNED, de ses R\u00e8glement et Politiques,de ses processus, de ses normes et de ses protocoles.&nbsp; Il assurera le leadership dans l&rsquo;\u00e9laboration de politiques et proc\u00e9dures op\u00e9rationnelles subs\u00e9quentes et du contr\u00f4le de leur mise en \u009cuvre.<\/p>\n<p>M. Pink a plus de 25 ans d&rsquo;exp\u00e9rience comme avocat et professionnel. Il a r\u00e9cemment servi en tant que directeur g\u00e9n\u00e9ral de Nelligan O&rsquo;Brien Payne LLP Law Offices, o\u00f9 il s&rsquo;est construit une solide r\u00e9putation pour sa capacit\u00e9 \u00e0 cr\u00e9er une valeur accrue pour les actionnaires et a re\u00e7u des \u00e9loges pour sa saine gestion et ses aptitudes inspirantes en motivation. Au cours de sa carri\u00e8re il a occup\u00e9 des postes de direction chez Anthony Group of Companies. M. Pink d\u00e9tient un LLM.de l&rsquo;Universit\u00e9 York, M.B.A., d&rsquo;Upper Iowa University, LLB., de l&rsquo;Universit\u00e9 Dalhousie, Dipl\u00f4me avec sp\u00e9cialisation, arts, de sociologie et de criminologie, de St. Mary&rsquo;s University, un baccalaur\u00e9at en commerce avec concentration en marketing et en administration des affaires, de l&rsquo;Universit\u00e9 St. Mary&rsquo;s et un baccalaur\u00e9at d\u2019arts en sociologie de l&rsquo;Universit\u00e9 St. Mary&rsquo;s.<\/p>\n<p>M. Pink r\u00e9pondra directement au Directeur g\u00e9n\u00e9ral et Registraire le Dr Jack Gerrow et sera un membre cl\u00e9 de l&rsquo;\u00e9quipe ex\u00e9cutive du BNED.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Bureau national d&rsquo;examen dentaire du Canada (BNED) est heureux d&rsquo;annoncer que Steven Pink se joindra au BNED dans un double r\u00f4le de conseiller juridique \u00e0 l&rsquo;interne et directeur des&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3547","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3547"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3547\/revisions"}],"predecessor-version":[{"id":3560,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3547\/revisions\/3560"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}