{"id":3544,"date":"2016-04-21T00:00:00","date_gmt":"2021-06-25T14:31:52","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/resultats-des-examens-de-certification\/"},"modified":"2021-06-25T10:33:56","modified_gmt":"2021-06-25T14:33:56","slug":"resultats-des-examens-de-certification","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2016\/04\/21\/resultats-des-examens-de-certification\/","title":{"rendered":"R\u00e9sultats des examens de certification"},"content":{"rendered":"<p>Les r\u00e9sultats de l\u0091Examen \u00e9crit et de l\u2019ECOS de mars 2016 sont maintenant publi\u00e9s.<\/p>\n<p>Voir l\u2019historiques des taux de r\u00e9ussite sous l\u2019onglet <a href=\"https:\/\/www.ndeb.ca\/fr\/ressources\/historique-des-taux-de-reussite\">Mat\u00e9riel de r\u00e9f\u00e9rence et ressources<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9sultats de l\u0091Examen \u00e9crit et de l\u2019ECOS de mars 2016 sont maintenant publi\u00e9s. Voir l\u2019historiques des taux de r\u00e9ussite sous l\u2019onglet Mat\u00e9riel de r\u00e9f\u00e9rence et ressources.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3544","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3544"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3544\/revisions"}],"predecessor-version":[{"id":3557,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3544\/revisions\/3557"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}