{"id":3543,"date":"2016-05-02T00:00:00","date_gmt":"2021-06-25T14:31:52","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/changements-aux-demandes-d%c2%92accommodements-speciaux\/"},"modified":"2021-06-25T10:33:56","modified_gmt":"2021-06-25T14:33:56","slug":"changements-aux-demandes-daccommodements-speciaux","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2016\/05\/02\/changements-aux-demandes-daccommodements-speciaux\/","title":{"rendered":"Changements aux demandes d\u2019accommodements sp\u00e9ciaux"},"content":{"rendered":"<p>Le BNED a r\u00e9vis\u00e9 ses politiques en mati\u00e8re d\u2019accommodements. Les individus peuvent faire une demande d\u2019accommodement pour une invalidit\u00e9 ou un probl\u00e8me de sant\u00e9 document\u00e9s, ou pour une raison religieuse.&nbsp; Les demandes d\u2019accommodement sont confidentielles. Les accommodements sp\u00e9ciaux sont accord\u00e9s sur une base individuelle et d\u00e9pendent de la nature et de l&rsquo;ampleur de la demande, de la documentation fournie et des exigences de l&rsquo;\u00e9valuation\/examen. Les informations expliquant comment soumettre une demande se trouvent dans la section <a href=\"https:\/\/www.ndeb.ca\/fr\/accommodements-speciaux\">Accommodements speciaux<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le BNED a r\u00e9vis\u00e9 ses politiques en mati\u00e8re d\u2019accommodements. Les individus peuvent faire une demande d\u2019accommodement pour une invalidit\u00e9 ou un probl\u00e8me de sant\u00e9 document\u00e9s, ou pour une raison religieuse.&nbsp;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3543","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3543"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3543\/revisions"}],"predecessor-version":[{"id":3554,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3543\/revisions\/3554"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}