{"id":3540,"date":"2016-11-29T00:00:00","date_gmt":"2021-06-25T14:31:47","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/le-dr-doug-mackey-elue-presidente-du-bned\/"},"modified":"2021-06-25T10:34:00","modified_gmt":"2021-06-25T14:34:00","slug":"le-dr-doug-mackey-elue-presidente-du-bned","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2016\/11\/29\/le-dr-doug-mackey-elue-presidente-du-bned\/","title":{"rendered":"Le Dr Doug Mackey \u00e9lue pr\u00e9sidente du BNED"},"content":{"rendered":"<p>Le Bureau national d\u2019examen dentaire du Canada (BNED) a le plaisir d&rsquo;annoncer l\u2019\u00e9lection du Dr Doug Mackey comme pr\u00e9sident du NDEB \u00e0 la r\u00e9union annuelle du 22 octobre 2016.<\/p>\n<p>Dr Mackey est originaire de St. John&rsquo;s (Terre-Neuve et Labrador) et a \u00e9tudi\u00e9 la musique et l&rsquo;\u00e9ducation \u00e0 Memorial University. En 1993, il est d\u00e9m\u00e9nag\u00e9 \u00e0 Halifax, en Nouvelle-\u00c9cosse, o\u00f9 il a \u00e9tudi\u00e9 \u00e0 Dalhousie University et y a obtenu un baccalaur\u00e9at en sciences en 1995 et un doctorat en chirurgie dentaire en 1999. Depuis l\u2019obtention de son dipl\u00f4me, le docteur Mackey pratique \u00e0 temps plein en cabinet priv\u00e9e dans la vall\u00e9e d&rsquo;Annapolis, en Nouvelle \u00c9cosse.<\/p>\n<p>En 2008, le Dr Mackey a \u00e9t\u00e9 nomm\u00e9 repr\u00e9sentant du Conseil provincial dentaire de la Nouvelle-\u00c9cosse (PDBNS) au conseil d&rsquo;administration du BNED. Depuis ce temps, il a occup\u00e9 divers postes \u00e0 titre d&rsquo;examinateur et en tant que membre de plusieurs comit\u00e9s. En 2012, le Dr Mackey a \u00e9t\u00e9 \u00e9lu au Comit\u00e9 ex\u00e9cutif du BNED et de 2014 \u00e0 2016 a \u00e9t\u00e9 tr\u00e9sorier et vice-pr\u00e9sident du conseil. \u00abJ&rsquo;ai eu le plaisir de travailler avec le Dr. Mackey \u00e0 diff\u00e9rents titres au fil des ans. Le Dr Mackey accepte chaque nouveau d\u00e9fi avec enthousiasme et professionnalisme et j\u2019ai h\u00e2te de travailler avec lui dans son nouveau r\u00f4le de pr\u00e9sident.\u00bb Dr Jack Gerrow, directeur g\u00e9n\u00e9ral et registraire.<\/p>\n<p>Au niveau provincial, le Dr. Mackey est le pr\u00e9sident du comit\u00e9 de formation continue obligatoire du PDBNS et il est instructeur \u00e0 temps partiel \u00e0 la facult\u00e9 de m\u00e9decine dentaire de Dalhousie University. De plus, il continue d\u2019utiliser sa formation musicale dans divers projets communautaires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Bureau national d\u2019examen dentaire du Canada (BNED) a le plaisir d&rsquo;annoncer l\u2019\u00e9lection du Dr Doug Mackey comme pr\u00e9sident du NDEB \u00e0 la r\u00e9union annuelle du 22 octobre 2016. Dr&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3540","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3540"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3540\/revisions"}],"predecessor-version":[{"id":3579,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3540\/revisions\/3579"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}