{"id":3527,"date":"2017-06-08T00:00:00","date_gmt":"2021-06-25T14:31:47","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/les-frais-dinscription-pour-le-processus-dequivalence-en-hausse\/"},"modified":"2021-06-25T10:34:00","modified_gmt":"2021-06-25T14:34:00","slug":"les-frais-dinscription-pour-le-processus-dequivalence-en-hausse","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2017\/06\/08\/les-frais-dinscription-pour-le-processus-dequivalence-en-hausse\/","title":{"rendered":"Les frais d&rsquo;inscription pour le Processus d&rsquo;\u00e9quivalence en hausse"},"content":{"rendered":"<p>\u00c0 compter du 1er juillet 2017, les frais d\u2019inscription pour le Processus d&rsquo;\u00e9quivalence augmenteront \u00e0 1100 $. La liste compl\u00e8te des frais pour le Processus d&rsquo;\u00e9quivalence peut \u00eatre consult\u00e9e dans la section des droits pour le processus d\u2019\u00e9quivalence du site Web du BNED.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 compter du 1er juillet 2017, les frais d\u2019inscription pour le Processus d&rsquo;\u00e9quivalence augmenteront \u00e0 1100 $. La liste compl\u00e8te des frais pour le Processus d&rsquo;\u00e9quivalence peut \u00eatre consult\u00e9e dans&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3527","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3527"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3527\/revisions"}],"predecessor-version":[{"id":3577,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3527\/revisions\/3577"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}