{"id":3501,"date":"2018-05-07T00:00:00","date_gmt":"2021-06-25T14:31:34","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/mai-2018-evaluation-des-habiletes-cliniques\/"},"modified":"2021-06-25T10:34:05","modified_gmt":"2021-06-25T14:34:05","slug":"mai-2018-evaluation-des-habiletes-cliniques","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2018\/05\/07\/mai-2018-evaluation-des-habiletes-cliniques\/","title":{"rendered":"Mai 2018 &#8211; \u00c9valuation des habilet\u00e9s cliniques"},"content":{"rendered":"<p>L&rsquo;\u00c9HC de juin approche rapidement. Si vous vous pr\u00e9parez pour l&rsquo;\u00e9valuation, notez que le BNED a apport\u00e9 des changements importants \u00e0 l&rsquo;administration de l\u2019\u00c9HC, comme l&rsquo;\u00e9valuation de l&rsquo;hygi\u00e8ne des mains, de nouvelles r\u00e8gles sur les t\u00e9l\u00e9phones cellulaires et les montres intelligentes en clinique et des changements \u00e0 l\u2019heure de fin de l&rsquo;\u00e9valuation. Ces changements et d&rsquo;autres peuvent \u00eatre trouv\u00e9s dans le Protocole d&rsquo;\u00c9valuation des habilet\u00e9s cliniques de juin 2018.<\/p>\n<p>Il est important de lire attentivement le protocole d&rsquo;\u00e9valuation avant chaque administration.<\/p>\n<p>L&rsquo;orientation pour l&rsquo;\u00e9valuation de juin 2018 diff\u00e9rera \u00e9galement des administrations ant\u00e9rieures. Le BNED a produit une vid\u00e9o d&rsquo;orientation que les participants devront visionner avant l&rsquo;\u00e9valuation. Les personnes inscrites \u00e0 l&rsquo;\u00c9HC recevront des instructions sp\u00e9cifiques pour acc\u00e9der \u00e0 la vid\u00e9o lorsque la date de l\u2019\u00c9HC approchera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00c9HC de juin approche rapidement. Si vous vous pr\u00e9parez pour l&rsquo;\u00e9valuation, notez que le BNED a apport\u00e9 des changements importants \u00e0 l&rsquo;administration de l\u2019\u00c9HC, comme l&rsquo;\u00e9valuation de l&rsquo;hygi\u00e8ne des mains,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3501","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3501"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3501\/revisions"}],"predecessor-version":[{"id":3614,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3501\/revisions\/3614"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}