{"id":3491,"date":"2018-08-17T00:00:00","date_gmt":"2021-06-25T14:31:34","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/pourquoi-cela-prend-il-autant-de-temps-pour-obtenir-mes-resultats\/"},"modified":"2021-06-25T10:34:06","modified_gmt":"2021-06-25T14:34:06","slug":"pourquoi-cela-prend-il-autant-de-temps-pour-obtenir-mes-resultats","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2018\/08\/17\/pourquoi-cela-prend-il-autant-de-temps-pour-obtenir-mes-resultats\/","title":{"rendered":"Pourquoi cela prend-il autant de temps pour obtenir mes r\u00e9sultats?"},"content":{"rendered":"<p>Il n&rsquo;est pas rare que le BNED re\u00e7oive de nombreuses demandes de renseignements apr\u00e8s l&rsquo;administration d&rsquo;un examen. Une question r\u00e9guli\u00e8rement pos\u00e9e est \u00ab pourquoi le BNED met-il si longtemps \u00e0 fournir les r\u00e9sultats?<\/p>\n<p>Le traitement des r\u00e9sultats du BNED est fait en profondeur et est con\u00e7u pour s&rsquo;assurer que les r\u00e9sultats communiqu\u00e9s aux candidats\/participants sont exacts et refl\u00e8tent le rendement du candidat\/participant au test.<\/p>\n<p>Comme les examens\/\u00e9valuations du BNED sont actuellement offerts en format papier partout au pays, tous les documents d&rsquo;examen\/\u00e9valuation doivent d&rsquo;abord \u00eatre renvoy\u00e9s au bureau du BNED et compar\u00e9s. Les feuilles- r\u00e9ponses sont ensuite num\u00e9ris\u00e9es et le personnel confirme les informations d&rsquo;identification manquantes ou les num\u00e9ros de version manquants.<\/p>\n<p>Une fois toutes les donn\u00e9es saisies, un calcul et une validation initiale des r\u00e9sultats ont lieu. Ce processus comprend la v\u00e9rification d&rsquo;un nombre pr\u00e9d\u00e9termin\u00e9 de feuilles- r\u00e9ponses \u00e0 l&rsquo;aide de la correction manuelle pour confirmer qu&rsquo;aucune erreur de correction \u00e9lectronique ne se produise.<\/p>\n<p>Une s\u00e9rie de rapports statistiques sont ensuite g\u00e9n\u00e9r\u00e9s, et l\u2019examinateur -en-chef et les examinateurs adjoints&nbsp; examinent les rapports ainsi que l&rsquo;analyse diff\u00e9rentielle entre les versions anglaise et fran\u00e7aise afin d&rsquo;identifier toute anomalie.<\/p>\n<p>Les r\u00e9sultats sont ensuite v\u00e9rifi\u00e9s une derni\u00e8re fois avant d&rsquo;\u00eatre remis aux candidats\/participants. En g\u00e9n\u00e9ral, ce processus prend entre quatre et six semaines, et bien que le BNED comprend l&rsquo;anticipation de ceux qui attendent leurs r\u00e9sultats, l&rsquo;exactitude du traitement des r\u00e9sultats est primordiale et fait en sorte que le BNED puisse \u00eatre certain qu&rsquo;il n&rsquo;y a pas d&rsquo;erreurs.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il n&rsquo;est pas rare que le BNED re\u00e7oive de nombreuses demandes de renseignements apr\u00e8s l&rsquo;administration d&rsquo;un examen. Une question r\u00e9guli\u00e8rement pos\u00e9e est \u00ab pourquoi le BNED met-il si longtemps \u00e0&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3491","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3491"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3491\/revisions"}],"predecessor-version":[{"id":3616,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3491\/revisions\/3616"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}