{"id":3471,"date":"2019-02-04T00:00:00","date_gmt":"2021-06-25T14:31:29","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/l%c2%92eccsd-est-ce-vendredi-2\/"},"modified":"2021-06-25T10:34:09","modified_gmt":"2021-06-25T14:34:09","slug":"leccsd-est-ce-vendredi-2","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2019\/02\/04\/leccsd-est-ce-vendredi-2\/","title":{"rendered":"L\u2019ECCSD est ce vendredi"},"content":{"rendered":"<p>L\u2019examen des connaissances communes (ECCSD) aura lieu ce vendredi 8 f\u00e9vrier 2019.<\/p>\n<p>Il sera administr\u00e9 par les centres d\u2019examen <a href=\"https:\/\/www.prometric.com\/en-us\/Pages\/home.aspx\" target=\"_blank\" rel=\"noopener\">Prometric<\/a> \u00e0 travers le Canada et comprend une combinaison de 95 -100 questions \u00e0 choix multiples de r\u00e9ponses uniques ou multiples au courant d\u2019une session de 3&nbsp;h.<\/p>\n<p>En pr\u00e9paration pour l\u2019examen, assurez-vous de lire le <a href=\"\/sites\/ndeb\/files\/pdf\/Protocols\/2019\/eccsd_electronique_2019.pdf\" target=\"_blank\" rel=\"noopener\">Protocole de l\u2019Examen des connaissances communes \u00e0 toutes les sp\u00e9cialit\u00e9s dentaires 2019<\/a> et familiarisez-vous avec les proc\u00e9dures d\u2019enregistrement de <a href=\"https:\/\/www.prometric.com\/en-us\/Pages\/home.aspx\" target=\"_blank\" rel=\"noopener\">Prometric<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019examen des connaissances communes (ECCSD) aura lieu ce vendredi 8 f\u00e9vrier 2019. Il sera administr\u00e9 par les centres d\u2019examen Prometric \u00e0 travers le Canada et comprend une combinaison de 95&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3471","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3471"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3471\/revisions"}],"predecessor-version":[{"id":3636,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3471\/revisions\/3636"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}