{"id":3433,"date":"2019-09-26T00:00:00","date_gmt":"2021-06-25T14:31:17","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/la-date-limite-des-inscriptions-pour-les-examens-de-novembre-se-rapproche-rapidement\/"},"modified":"2021-06-25T10:34:16","modified_gmt":"2021-06-25T14:34:16","slug":"la-date-limite-des-inscriptions-pour-les-examens-de-novembre-se-rapproche-rapidement","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2019\/09\/26\/la-date-limite-des-inscriptions-pour-les-examens-de-novembre-se-rapproche-rapidement\/","title":{"rendered":"La date limite des inscriptions pour les examens de novembre se rapproche rapidement!"},"content":{"rendered":"<p>La date limite des inscriptions pour l&rsquo;Examen \u00e9crit, ECOS, et \u00c9valuation des jugement cliniques (EJC)&nbsp;de novembre se rapproche rapidement.<\/p>\n<p>L\u2019inscription sera selon le principe premier arriv\u00e9, premier servi, car les places sont limit\u00e9es. Pour s\u2019inscrire, veuillez vous connecter \u00e0 votre profil en ligne.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La date limite des inscriptions pour l&rsquo;Examen \u00e9crit, ECOS, et \u00c9valuation des jugement cliniques (EJC)&nbsp;de novembre se rapproche rapidement. L\u2019inscription sera selon le principe premier arriv\u00e9, premier servi, car les&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3433","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3433"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3433\/revisions"}],"predecessor-version":[{"id":3685,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3433\/revisions\/3685"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}