{"id":3426,"date":"2019-11-07T00:00:00","date_gmt":"2021-06-25T14:31:17","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/le-bned-souhaite-la-bienvenue-a-une-nouvelle-representante-publique\/"},"modified":"2021-06-25T10:34:14","modified_gmt":"2021-06-25T14:34:14","slug":"le-bned-souhaite-la-bienvenue-a-une-nouvelle-representante-publique","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2019\/11\/07\/le-bned-souhaite-la-bienvenue-a-une-nouvelle-representante-publique\/","title":{"rendered":"Le BNED souhaite la bienvenue \u00e0 une nouvelle Repr\u00e9sentante publique"},"content":{"rendered":"<p>Mme Jan Sheppard Kutcher de Herring Cove, N.-\u00c9 a \u00e9t\u00e9 r\u00e9cemment \u00e9lue pour se joindre au Bureau du BNED dans le r\u00f4le de Repr\u00e9sentante publique pour un mandat de trois ans, qui se termine en novembre 2022. Mme Sheppard Kutcher remplace Mme Polly Pachu du Manitoba, qui aura compl\u00e9t\u00e9 son mandat de trois ans ce novembre.<\/p>\n<p>Mme Sheppard Kutcher a si\u00e9g\u00e9 \u00e0 titre de copr\u00e9sidente du <em>Internationally Educated Dental Professional (IEDP) Working Group<\/em> au <em>Provincial Dental Board of Nova Scotia<\/em> jusqu\u2019au moment de sa retraite cette derni\u00e8re ann\u00e9e. Le IEDP assiste aux dentistes form\u00e9s \u00e0 l&rsquo;\u00e9tranger \u00e0 se naviguer vers une licence \u00e0 travers des diff\u00e9rentes initiatives.<\/p>\n<p>Selon Dr Martin Gillis, Registraire pour le <em>Provincial Dental Board of Nova Scotia<\/em>, \u00ab&nbsp;En tant que copr\u00e9sidente, Jan \u00e9tait instrumentale avec son approche orient\u00e9e sur l&rsquo;action et les solutions et sa r\u00e9flexion strat\u00e9gique pour le d\u00e9veloppement et la viabilit\u00e9 des projets IEDP. Ce&nbsp;groupe \u00e9taient tr\u00e8s privil\u00e9gi\u00e9s d\u2019avoir une personne autant d\u00e9vou\u00e9e, empathique et g\u00e9n\u00e9reuse \u00e0 supporter leurs objectifs qui est refl\u00e9t\u00e9e par le succ\u00e8s qu\u2019ils ont eux \u00e0 recevoir un permis en Nouvelle-\u00c9cosse.&nbsp;\u00bb<\/p>\n<p>La Repr\u00e9sentante publique de BNED agit en tant qu\u2019observatrice officielle au Bureau et un membre avec droit de vote du Comite d\u2019examens.<\/p>\n<p>Le BNED souhaite \u00e0 remercier Mme Pachu pour son travail acharn\u00e9 et d\u00e9vouement au cours de son mandat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mme Jan Sheppard Kutcher de Herring Cove, N.-\u00c9 a \u00e9t\u00e9 r\u00e9cemment \u00e9lue pour se joindre au Bureau du BNED dans le r\u00f4le de Repr\u00e9sentante publique pour un mandat de trois&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3426","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3426"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3426\/revisions"}],"predecessor-version":[{"id":3670,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3426\/revisions\/3670"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}