{"id":3409,"date":"2020-01-30T00:00:00","date_gmt":"2021-06-25T14:31:12","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/le-bned-accueille-sa-nouvelle-directrice-des-examens\/"},"modified":"2021-06-25T10:34:16","modified_gmt":"2021-06-25T14:34:16","slug":"le-bned-accueille-sa-nouvelle-directrice-des-examens","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2020\/01\/30\/le-bned-accueille-sa-nouvelle-directrice-des-examens\/","title":{"rendered":"Le BNED accueille sa nouvelle Directrice des Examens"},"content":{"rendered":"<p>Le Bureau national d&rsquo;examen dentaire (BNED) est heureux d&rsquo;annoncer que la Docteure Caroline Tram Nguyen se joindra au BNED&nbsp;<img decoding=\"async\" alt=\"\" src=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/wp-content\/uploads\/2021\/06\/caroline_portrait_high_def.png\" style=\"width: 200px; height: 246px; float: right;margin-left:30px;margin-bottom:30px\">\u00e0 titre de Directrice des Examens. \u00ab&nbsp;Caroline a d\u00e9j\u00e0 d\u00e9montr\u00e9 qu\u2019elle pouvait jouer un r\u00f4le important dans l\u2019\u00e9laboration de notre nouvel examen de certification&nbsp;\u00bb, affirme la Dre Marie Dagenais, directrice g\u00e9n\u00e9rale et registraire du BNED. \u00ab&nbsp;Elle va maintenant jouer un r\u00f4le cl\u00e9 au niveau des examens de sp\u00e9cialit\u00e9s dont le BNED est maintenant responsable.&nbsp;\u00bb<\/p>\n<p>Dre Nguyen est impliqu\u00e9e au sein du BNED depuis plusieurs ann\u00e9es en tant qu&rsquo;examinatrice. Son implication au niveau des organismes professionnels s&rsquo;\u00e9tend au-del\u00e0 du BNED, dans des associations telles que l\u2019Association des Prosthodontistes du Canada, dont elle fut pr\u00e9sidente de 2016-2018, l&rsquo;Association Canadienne des Sp\u00e9cialit\u00e9s Dentaires, le Coll\u00e8ge Royal des Chirurgiens Dentistes du Canada, et l&rsquo;American College of Prosthodontists. Dre Nguyen d\u00e9tient un DMD de l&rsquo;Universit\u00e9 de Montr\u00e9al, une maitrise en sciences et prosthodontie de l&rsquo;University of Maryland, et un fellowship en prosthodontie maxillofaciale de l&rsquo;University of Texas M.D. Anderson Cancer Center. Elle a \u00e9t\u00e9 professeure \u00e0 l\u2019University of British Columbia depuis 2010 et continuera d\u2019exercer en milieu hospitalier \u00e0 Ottawa.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Bureau national d&rsquo;examen dentaire (BNED) est heureux d&rsquo;annoncer que la Docteure Caroline Tram Nguyen se joindra au BNED&nbsp;\u00e0 titre de Directrice des Examens. \u00ab&nbsp;Caroline a d\u00e9j\u00e0 d\u00e9montr\u00e9 qu\u2019elle pouvait&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3409","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3409"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3409\/revisions"}],"predecessor-version":[{"id":3687,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3409\/revisions\/3687"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}