{"id":3398,"date":"2020-03-27T00:00:00","date_gmt":"2021-06-25T14:31:06","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/l%c2%92ehc-de-juin-annulee\/"},"modified":"2021-06-25T10:34:21","modified_gmt":"2021-06-25T14:34:21","slug":"lehc-de-juin-annulee","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2020\/03\/27\/lehc-de-juin-annulee\/","title":{"rendered":"L\u2019\u00c9HC de juin annul\u00e9e"},"content":{"rendered":"<p>Le BNED continue de surveiller les d\u00e9veloppements de la pand\u00e9mie de la COVID-19 ainsi que les recommandations de la Sant\u00e9 publique.<\/p>\n<p>En se basant sur la situation actuelle, le BNED a pris la d\u00e9cision d\u2019annuler l\u2019\u00c9valuation des habilet\u00e9s cliniques (\u00c9HC) de juin 2020.<\/p>\n<p>Le BNED continuera d\u2019\u00e9valuer quels services devront \u00eatre suspendus ou annul\u00e9s \u00e0 mesure que les nouvelles informations arriveront.&nbsp;<\/p>\n<p>Veuillez consulter notre page <a href=\"\/fr\/mise-jour-covid-19\">Mise \u00e0 jour COVID-19<\/a> pour l\u2019information la plus r\u00e9cente sur les services du BNED qui sont affect\u00e9s par la pand\u00e9mie.&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le BNED continue de surveiller les d\u00e9veloppements de la pand\u00e9mie de la COVID-19 ainsi que les recommandations de la Sant\u00e9 publique. En se basant sur la situation actuelle, le BNED&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3398","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3398"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3398\/revisions"}],"predecessor-version":[{"id":3720,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3398\/revisions\/3720"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}