{"id":3362,"date":"2020-10-05T00:00:00","date_gmt":"2021-06-25T14:31:01","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/les-inscriptions-a-lexamen-ecrit-et-a-lecos-de-novembre-sont-desormais-fermees\/"},"modified":"2021-06-25T10:34:23","modified_gmt":"2021-06-25T14:34:23","slug":"les-inscriptions-a-lexamen-ecrit-et-a-lecos-de-novembre-sont-desormais-fermees","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2020\/10\/05\/les-inscriptions-a-lexamen-ecrit-et-a-lecos-de-novembre-sont-desormais-fermees\/","title":{"rendered":"Les inscriptions \u00e0 l&rsquo;Examen \u00e9crit et \u00e0 l&rsquo;ECOS de novembre sont d\u00e9sormais ferm\u00e9es"},"content":{"rendered":"<p>Les participants doivent s&rsquo;assurer de lire les <a href=\"\/fr\/ressources\/ressources-dexamen\" target=\"_blank\" rel=\"noopener\">protocoles d&rsquo;examen <\/a>avant chaque examen et se tenir inform\u00e9 des restrictions et des r\u00e8glements \u00e9tablis par les responsables de la sant\u00e9 publique de leur lieu d&rsquo;examen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les participants doivent s&rsquo;assurer de lire les protocoles d&rsquo;examen avant chaque examen et se tenir inform\u00e9 des restrictions et des r\u00e8glements \u00e9tablis par les responsables de la sant\u00e9 publique de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3362","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3362"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3362\/revisions"}],"predecessor-version":[{"id":3734,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3362\/revisions\/3734"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}