{"id":3360,"date":"2020-10-20T00:00:00","date_gmt":"2021-06-25T14:30:56","guid":{"rendered":"https:\/\/prelive.ndeb-bned.ca\/2021\/06\/25\/l%c2%92inscription-a-lejc-de-novembre-est-maintenant-fermee\/"},"modified":"2021-06-25T10:34:27","modified_gmt":"2021-06-25T14:34:27","slug":"linscription-a-lejc-de-novembre-est-maintenant-fermee","status":"publish","type":"post","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/2020\/10\/20\/linscription-a-lejc-de-novembre-est-maintenant-fermee\/","title":{"rendered":"L\u2019inscription \u00e0 l&rsquo;\u00c9JC de novembre est maintenant ferm\u00e9e"},"content":{"rendered":"<p>L\u2019inscription \u00e0 l\u2019\u00c9valuation du jugement clinique (\u00c9JC) de&nbsp;novembre&nbsp;est maintenant ferm\u00e9e.&nbsp;Il est rappel\u00e9 aux partcipants de lire le <a href=\"\/fr\/ressources\/ressources-dexamen\" target=\"_blank\" rel=\"noopener\">Protocole <\/a>d&rsquo;examen et de se tenir inform\u00e9es des restrictions et des r\u00e8glements \u00e9tablis par les responsables de la sant\u00e9 publique de leur lieu d&rsquo;examen.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019inscription \u00e0 l\u2019\u00c9valuation du jugement clinique (\u00c9JC) de&nbsp;novembre&nbsp;est maintenant ferm\u00e9e.&nbsp;Il est rappel\u00e9 aux partcipants de lire le Protocole d&rsquo;examen et de se tenir inform\u00e9es des restrictions et des r\u00e8glements \u00e9tablis&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3360","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=3360"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3360\/revisions"}],"predecessor-version":[{"id":3760,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/posts\/3360\/revisions\/3760"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=3360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/categories?post=3360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/tags?post=3360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}