{"id":99263,"date":"2026-07-20T12:50:11","date_gmt":"2026-07-20T16:50:11","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?page_id=99263"},"modified":"2026-07-20T13:09:22","modified_gmt":"2026-07-20T17:09:22","slug":"reglements-et-politiques-2","status":"publish","type":"page","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/ressources\/reglements-et-politiques-2\/","title":{"rendered":"R\u00e8glements et Politiques"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1743795465144{padding-top: 90px !important;padding-bottom: 0px !important;}\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbflex-box\u00a0\u00bb background_color=\u00a0\u00bb#F2F1F1&Prime;][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>R\u00e8glements du BNED<\/h3>\n<p>Les R\u00e8glements du BNED r\u00e9gissent le fonctionnement de l\u2019organisation, y compris les droits et les responsabilit\u00e9s des membres du BNED, des comit\u00e9s, des examens et des proc\u00e9dures d\u2019appel. Les R\u00e8glements sont r\u00e9vis\u00e9s par le Comit\u00e9 des R\u00e8glements et approuv\u00e9s par les membres du Bureau.<\/p>\n<p>T\u00e9l\u00e9chargez le <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/wp-content\/uploads\/2026\/07\/2025_10_25_Reglement-1_Gouvernance_Approuve-mai-2026-1.pdf\" target=\"_blank\" rel=\"noopener\">r\u00e8glement n\u00b0 1 Gouvernance du BNED<\/a> au format PDF.<\/p>\n<p>T\u00e9l\u00e9chargez le <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/wp-content\/uploads\/2026\/07\/2026-07-13-Reglement-2_Processus-de-certification-et-dequivalence_Approve-mai-2026.pdf\" target=\"_blank\" rel=\"noopener\">r\u00e8glement n\u00b0 2 Processus de certification et d&rsquo;\u00e9quivalence du BNED<\/a> au format PDF.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb64px\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>Loi du Parlement<\/h3>\n<p>Le BNED a \u00e9t\u00e9 cr\u00e9\u00e9 par une loi du Parlement en 1952 avec mandat d\u2019\u00e9tablir pour les dentistes g\u00e9n\u00e9ralistes les conditions de qualification \u00e0 une norme nationale de comp\u00e9tence et d\u2019\u00e9mettre un certificat aux dentistes ayant acc\u00e9d\u00e9 \u00e0 la norme.<\/p>\n<p>T\u00e9l\u00e9chargez la <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/wp-content\/uploads\/2021\/03\/actsf.pdf\" target=\"_blank\" rel=\"noopener\">loi du Parlement.<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1744381453434{margin-right: 420px !important;margin-left: 270px !important;padding-top: 40px !important;padding-bottom: 0px !important;}\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_empty_space][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>Politiques et proc\u00e9dures<\/h3>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_accordion active_tab=\u00a0\u00bbfalse\u00a0\u00bb collapsible=\u00a0\u00bbyes\u00a0\u00bb style=\u00a0\u00bbaccordion\u00a0\u00bb][vc_accordion_tab title=\u00a0\u00bb1. G\u00e9n\u00e9rales\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]1.1 Sauf indication contraire du contexte, les termes au singulier ou au genre masculin incluent le pluriel et le genre f\u00e9minin, selon le cas, et vice versa.<\/p>\n<p>1.2 En mati\u00e8re de calcul des d\u00e9lais, les dispositions suivantes s\u2019appliquent :<\/p>\n<p style=\"margin-left: 40px;\">1.2.1. lorsqu\u2019il s\u2019agit de calculer le nombre de jours entre deux \u00e9v\u00e9nements, tels qu\u2019une d\u00e9cision et le d\u00e9lai de recours, le jour o\u00f9 survient le premier \u00e9v\u00e9nement est exclu, mais celui o\u00f9 survient le second \u00e9v\u00e9nement est inclus ; et<\/p>\n<p style=\"margin-left: 40px;\">1.2.2. si le d\u00e9lai expire un jour f\u00e9ri\u00e9, il est report\u00e9 au premier jour ouvrable suivant ce jour f\u00e9ri\u00e9.<\/p>\n<p>1.3 On peut obtenir les politiques et proc\u00e9dures relatives aux examens et aux appels en fran\u00e7ais et en anglais et les deux versions ont le m\u00eame effet juridique. En cas de contradiction entre les versions fran\u00e7aise et anglaise, ou en cas d\u2019erreur de traduction, la version anglaise pr\u00e9vaudra.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb2. D\u00e9finitions\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]2.1 Le terme \u00ab jour ouvrable \u00bb d\u00e9signe tout jour qui n\u2019est pas un jour f\u00e9ri\u00e9.<\/p>\n<p>2.2 Le terme \u00ab dossier m\u00e9dical \u00bb d\u00e9signe tout dossier conforme aux dispositions de la partie VI des pr\u00e9sentes politiques et proc\u00e9dures.<\/p>\n<p>2.3 Le terme \u00ab professionnel de sant\u00e9 \u00bb d\u00e9signe un professionnel de sant\u00e9 qui d\u00e9tient ou d\u00e9tenait, au moment pertinent, un agr\u00e9ment d\u00e9livr\u00e9 par l\u2019organisme de r\u00e9glementation des professionnels de sant\u00e9 comp\u00e9tent.<\/p>\n<p>2.4 Le terme \u00ab jour f\u00e9ri\u00e9 \u00bb d\u00e9signe tout samedi ou dimanche, le jour de l\u2019An, la Journ\u00e9e de la famille, le Vendredi saint, le lundi de P\u00e2ques, la f\u00eate de la Reine, la f\u00eate du Canada, d\u00e9sistements la f\u00eate du Travail, le jour de l\u2019Action de gr\u00e2ce, le jour du Souvenir, le jour de No\u00ebl et le lendemain de No\u00ebl.<\/p>\n<p>2.5 Le terme \u00ab Personnel sur place \u00bb d\u00e9signe un surveillant, un surveillant d\u2019examen, un administrateur d\u2019examen ou toute autre personne charg\u00e9e de l\u2019administration ou de la supervision d\u2019un examen.[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>II. Statut de candidat<\/h3>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_accordion active_tab=\u00a0\u00bbfalse\u00a0\u00bb collapsible=\u00a0\u00bbyes\u00a0\u00bb style=\u00a0\u00bbaccordion\u00a0\u00bb][vc_accordion_tab title=\u00a0\u00bb3. Consid\u00e9ration sp\u00e9ciale\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Admissibilit\u00e9<\/h5>\n<p>3.1 Une personne qui :<\/p>\n<p style=\"margin-left: 40px;\">3.1.1. est titulaire d\u2019un permis d\u2019exercice de la m\u00e9decine dentaire hors du Canada et dont la date d\u2019obtention du dipl\u00f4me ou d\u2019ach\u00e8vement d\u2019un programme agr\u00e9\u00e9, d\u2019un programme agr\u00e9\u00e9 de qualification ou d\u2019obtention de dipl\u00f4me, ou d\u2019un programme formation passerelle vers la pratique dentaire au Canada (FPPDC), remonte \u00e0 plus de soixante (60) mois avant la date de l\u2019examen de l\u2019auquel elle s\u2019inscrit, doit pr\u00e9senter une demande au Comit\u00e9 ex\u00e9cutif pour devenir candidate \u00e0 la certification du Bureau ; ou<\/p>\n<p style=\"margin-left: 40px;\">3.1.2. a cess\u00e9 d\u2019\u00eatre candidat \u00e0 la certification conform\u00e9ment \u00e0 l\u2019article 7.4 du r\u00e8glement n\u00b0 2, n\u2019ayant pas r\u00e9ussi l\u2019ECOS Virtuel dans les soixante (60) mois suivant la date de<\/p>\n<p style=\"margin-left: 80px;\">(a) obtention de son dipl\u00f4me ou de la fin de ses \u00e9tudes dans le cadre d\u2019un programme agr\u00e9\u00e9, d\u2019un programme de qualification ou d\u2019obtention de dipl\u00f4me agr\u00e9\u00e9, ou d\u2019un programme agr\u00e9\u00e9 de formation passerelle vers la pratique dentaire au Canada (FPPDC) ; ou<\/p>\n<p style=\"margin-left: 80px;\">(b) la fin du processus d\u2019\u00e9quivalence,<br \/>\npeut pr\u00e9senter une demande au Comit\u00e9 ex\u00e9cutif, conform\u00e9ment \u00e0 l\u2019article 8.1 du R\u00e8glement n\u00b0 2, afin de b\u00e9n\u00e9ficier de Consid\u00e9rations sp\u00e9ciales et d\u2019\u00eatre d\u00e9sign\u00e9 candidat \u00e0 la certification (\u00ab Demande de Consid\u00e9rations sp\u00e9ciales \u00bb).<\/p>\n<h5>Soumissions des demandes<\/h5>\n<p>3.2 Si un demandeur de Consid\u00e9rations sp\u00e9ciales ne dispose pas d\u2019un compte NDEBConnect, il doit s\u2019acquitter des droits de demande d\u2019inscription et cr\u00e9er un compte NDEBConnect avant que sa demande de Consid\u00e9rations sp\u00e9ciales ne soit examin\u00e9e par le Comit\u00e9 ex\u00e9cutif.<\/p>\n<p>3.3 Le Comit\u00e9 ex\u00e9cutif n\u2019examinera que les demandes de Consid\u00e9rations sp\u00e9ciales compl\u00e8tes comprenant toutes les informations requises. Sous r\u00e9serve du droit du BNED d\u2019exiger des informations suppl\u00e9mentaires, les informations minimales requises dans une demande de Consid\u00e9rations sp\u00e9ciales sont les suivantes :<\/p>\n<p style=\"margin-left: 40px;\">3.3.1. un formulaire de demande de consid\u00e9rations sp\u00e9ciales sur support papier, rempli par le demandeur ; et<\/p>\n<p style=\"margin-left: 40px;\">3.3.2. les documents sur support papier \u00e9num\u00e9r\u00e9s dans le formulaire de demande de Consid\u00e9rations sp\u00e9ciales, y compris, sans s\u2019y limiter, la preuve d\u2019une pratique continue au cours des cinq (5) derni\u00e8res ann\u00e9es, ainsi que la preuve du maintien continu \u00e0 jour des connaissances dentaires et des comp\u00e9tences cliniques du candidat au cours des trois (3) derni\u00e8res ann\u00e9es, sous une forme et avec un contenu acceptable pour le BNED.<\/p>\n<p>3.4 La demande de consid\u00e9rations sp\u00e9ciales doit parvenir en version papier au BNED, \u00e0 ses bureaux d\u2019Ottawa, avant la date limite d\u2019inscription \u00e0 l\u2019examen pour lequel le candidat sollicitant des consid\u00e9rations sp\u00e9ciales souhaite s\u2019inscrire.<\/p>\n<h5>Cons\u00e9quences<\/h5>\n<p>3.5 Apr\u00e8s examen d\u2019une demande de consid\u00e9rations sp\u00e9ciales, le Comit\u00e9 ex\u00e9cutif peut :<\/p>\n<p style=\"margin-left: 40px;\">3.5.1. faire droit \u00e0 la demande de Consid\u00e9rations sp\u00e9ciales ;<\/p>\n<p style=\"margin-left: 40px;\">3.5.2. rejeter la demande de Consid\u00e9rations sp\u00e9ciales ; ou<\/p>\n<p style=\"margin-left: 40px;\">3.5.3. demander au demandeur de fournir des informations suppl\u00e9mentaires.<\/p>\n<p>3.6 La d\u00e9cision du Comit\u00e9 ex\u00e9cutif d&rsquo;accepter ou de rejeter une demande pour les Consid\u00e9rations sp\u00e9ciales est d\u00e9finitive.<\/p>\n<p>3.7 Le personnel du BNED communiquera la d\u00e9cision du Comit\u00e9 ex\u00e9cutif au candidat ayant d\u00e9pos\u00e9 une demande pour des consid\u00e9rations sp\u00e9ciales par courriel.<\/p>\n<p>3.8 Un candidat \u00e0 la certification dont la demande relative aux consid\u00e9rations sp\u00e9ciales a \u00e9t\u00e9 accept\u00e9e doit r\u00e9ussir l\u2019ECOS Virtuel dans un d\u00e9lai de soixante (60) mois \u00e0 compter de la date \u00e0 laquelle le BNED lui a communiqu\u00e9 la d\u00e9cision du Comit\u00e9 ex\u00e9cutif.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb4. Demande de prolongation du statut de candidat \u00e0 l\u2019\u00e9quivalence\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Conditions d\u2019\u00e9ligibilit\u00e9<\/h5>\n<p>4.1 Une personne qui cesse d\u2019\u00eatre un candidat \u00e0 l\u2019\u00e9quivalence conform\u00e9ment \u00e0 l\u2019article 16.8 du r\u00e8glement n\u00b0 2, pour ne pas avoir r\u00e9ussi l\u2019EDNCC dans les soixante (60) mois suivant la date \u00e0 laquelle elle a r\u00e9ussi pour la premi\u00e8re fois l\u2019\u00c9valuation du jugement clinique, peut demander au Comit\u00e9 ex\u00e9cutif une prolongation du d\u00e9lai de 60 mois pour r\u00e9ussir l\u2019EDNCC (\u00ab Demande de prolongation du statut de candidat \u00e0 l\u2019\u00e9quivalence \u00bb) si, au cours de la p\u00e9riode de soixante (60) mois pendant laquelle elle \u00e9tait candidate \u00e0 l\u2019\u00e9quivalence, elle a \u00e9t\u00e9 confront\u00e9e \u00e0 l\u2019une ou aux deux situations ci-apr\u00e8s :<\/p>\n<p style=\"margin-left: 40px;\">4.1.1. une situation m\u00e9dicale exceptionnelle qui l\u2019a emp\u00each\u00e9e trois reprises de s\u2019inscrire ou de participer \u00e0 l\u2019EDNCC ; et\/ou<\/p>\n<p style=\"margin-left: 40px;\">4.1.2. l\u2019impossibilit\u00e9 de s\u2019inscrire \u00e0 l\u2019EDNCC \u00e0 trois reprises ou plus.<\/p>\n<p><strong>Soumissions des demandes<\/strong><\/p>\n<p>4.2 Le Comit\u00e9 ex\u00e9cutif n\u2019examinera que les demandes de prolongation du statut de candidat \u00e0 l\u2019\u00e9quivalence compl\u00e8tes comprenant toutes les informations requises. Sous r\u00e9serve du droit du BNED d\u2019exiger des informations suppl\u00e9mentaires, les informations minimales requises dans une demande de prolongation du statut de candidat \u00e0 l\u2019\u00e9quivalence sont les suivantes :<\/p>\n<p style=\"margin-left: 40px;\">4.2.1. la soumission d\u2019un formulaire de \u00ab Demande de prolongation du statut de candidat \u00e0 l\u2019\u00e9quivalence \u00bb via le site web du BNED ;<\/p>\n<p style=\"margin-left: 40px;\">4.2.2. des informations d\u00e9montrant que la demande satisfait aux crit\u00e8res \u00e9nonc\u00e9s \u00e0 la section 4.1 des pr\u00e9sentes politiques et proc\u00e9dures ; et<\/p>\n<p style=\"margin-left: 40px;\">4.2.3. envoi par courriel des documents m\u00e9dicaux si le candidat a \u00e9t\u00e9 confront\u00e9 \u00e0 une situation m\u00e9dicale exceptionnelle.<\/p>\n<p>4.3 Pour les candidats demandant un d\u00e9lai suppl\u00e9mentaire en raison de leur incapacit\u00e9 \u00e0 s\u2019inscrire \u00e0 l\u2019EDNCC, le personnel du BNED examinera les registres d\u2019inscription afin de v\u00e9rifier qu\u2019\u00e0 chaque p\u00e9riode d\u2019inscription le candidat est entr\u00e9 dans la file d\u2019attente, mais n\u2019a pas \u00e9t\u00e9 transf\u00e9r\u00e9 vers la phase de s\u00e9lection des places.<\/p>\n<p><strong>Cons\u00e9quences<\/strong><\/p>\n<p>4.4 Apr\u00e8s examen d\u2019une demande de prolongation du statut de candidat \u00e0 l\u2019\u00e9quivalence, le Comit\u00e9 ex\u00e9cutif peut :<\/p>\n<p style=\"margin-left: 40px;\">4.4.1. faire droit \u00e0 la demande ;<\/p>\n<p style=\"margin-left: 40px;\">4.4.2. rejeter la demande ; ou<\/p>\n<p style=\"margin-left: 40px;\">4.4.3. demander au candidat de fournir des informations suppl\u00e9mentaires.<\/p>\n<p>4.5 Le personnel du BNED communiquera la d\u00e9cision du Comit\u00e9 ex\u00e9cutif au candidat par courriel.<\/p>\n<p>4.6 La d\u00e9cision du Comit\u00e9 ex\u00e9cutif d&rsquo;accepter ou de rejeter une demande de prolongation du statut de candidat \u00e0 l&rsquo;\u00e9quivalence est d\u00e9finitive.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb5. Comptes NDEBConnect inactifs\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]5.1 Les candidats n\u2019ayant aucune activit\u00e9 li\u00e9e aux examens pendant une p\u00e9riode de deux (2) ans (24 mois) verront le statut de leur compte NDEBConnect basculer en mode inactif.<\/p>\n<p>5.2 Le personnel du BNED informera les candidats par courriel lorsque leur compte NDEBConnect aura \u00e9t\u00e9 mis en statut \u00ab inactif \u00bb.<\/p>\n<p>5.3 D\u00e8s r\u00e9ception de cette notification, le candidat peut demander la r\u00e9activation de son compte NDEBConnect et s&rsquo;acquitter des droits requis. Si le candidat ne prend aucune mesure, son compte NDEBConnect restera inactif.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb6. Transfert au processus de certification\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]6.1 Les personnes qui ont entam\u00e9 mais n\u2019ont pas men\u00e9 \u00e0 bien le processus d\u2019\u00e9quivalence et qui, par la suite, deviennent \u00e9ligibles au processus de certification \u00e0 la suite d\u2019une formation compl\u00e9mentaire, doivent s\u2019acquitter des droits de demande d\u2019inscription au processus de certification afin de passer \u00e0 ce dernier et de devenir candidates \u00e0 la certification.[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>III. Examens<\/h3>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_accordion active_tab=\u00a0\u00bb\u00a0\u00bb collapsible=\u00a0\u00bbyes\u00a0\u00bb style=\u00a0\u00bbaccordion\u00a0\u00bb][vc_accordion_tab title=\u00a0\u00bb7. Inscription \u00e0 l&rsquo;EDNCC\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Processus<\/h5>\n<p>7.1 Les inscriptions \u00e0 l&rsquo;EDNCC s&rsquo;ouvriront en trois \u00e9tapes :<\/p>\n<p style=\"margin-left: 40px;\">7.1.1. \u00c9tape 1 : inscription des candidats ayant r\u00e9ussi la plus r\u00e9cente session de l\u2019\u00c9valuation du jugement clinique (\u00c9JC).<\/p>\n<p style=\"margin-left: 40px;\">7.1.2. \u00c9tape 2 : inscription des candidats disposant d\u2019une preuve approuv\u00e9e de citoyennet\u00e9 canadienne ou de r\u00e9sidence permanente.<\/p>\n<p style=\"margin-left: 40px;\">7.1.3. \u00c9tape 3 : inscription de tous les candidats remplissant les conditions d\u2019\u00e9ligibilit\u00e9 \u00e0 l\u2019EDNCC.<\/p>\n<p>7.2 Les candidats \u00e9ligibles qui ne s&rsquo;inscrivent pas lors de l\u2019\u00e9tape 1 peuvent s&rsquo;inscrire lors de l\u2019\u00e9tape 2 s&rsquo;ils sont citoyens canadiens ou r\u00e9sidents permanents, ou lors de l\u2019\u00e9tape 3 pour une tentative ult\u00e9rieure \u00e0 l&rsquo;EDNCC.<\/p>\n<p><strong>Soumissions des candidatures<\/strong><\/p>\n<p>7.3 Les candidats qui se trouvent dans une situation m\u00e9dicale exceptionnelle au moment o\u00f9 ils sont \u00e9ligibles \u00e0 l\u2019inscription \u00e0 l\u2019\u00e9tape 1 peuvent d\u00e9cliner l\u2019offre de s\u2019inscrire et adresser une demande sp\u00e9ciale au Comit\u00e9 ex\u00e9cutif afin que leur priorit\u00e9 d\u2019inscription soit report\u00e9e (\u00ab Demande de report de priorit\u00e9 \u00bb).<\/p>\n<p>7.4 Sous r\u00e9serve du droit du BNED d\u2019exiger des informations suppl\u00e9mentaires, toutes les demandes de report de priorit\u00e9 doivent \u00eatre accompagn\u00e9es d\u2019un dossier m\u00e9dical.<\/p>\n<p>7.5 Le Comit\u00e9 ex\u00e9cutif n\u2019examinera que les demandes de report de priorit\u00e9 compl\u00e8tes, comprenant toutes les informations requises.<\/p>\n<p><strong>Cons\u00e9quences<\/strong><\/p>\n<p>7.6 Apr\u00e8s examen d\u2019une demande de report de priorit\u00e9, le Comit\u00e9 ex\u00e9cutif peut :<\/p>\n<p style=\"margin-left: 40px;\">7.6.1. faire droit \u00e0 la demande ;<\/p>\n<p style=\"margin-left: 40px;\">7.6.2. rejeter la demande ; ou<\/p>\n<p style=\"margin-left: 40px;\">7.6.3. demander au candidat de fournir des informations suppl\u00e9mentaires.<\/p>\n<p>7.7 La d\u00e9cision du Comit\u00e9 ex\u00e9cutif d&rsquo;accepter ou de rejeter une demande de report de priorit\u00e9 est d\u00e9finitive.<\/p>\n<p>7.8 Le personnel du BNED communiquera la d\u00e9cision du Comit\u00e9 ex\u00e9cutif au candidat par courriel.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb8. Changement de langue d\u2019examen\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]8.1 Les demandes de changement de langue d\u2019examen doivent \u00eatre adress\u00e9es au BNED par courriel \u00e0 l\u2019adresse info@ndeb-bned.ca avant de passer l\u2019examen.<\/p>\n<p>8.2 Le personnel du BNED modifiera la langue d\u2019un examen pour un candidat \u00e0 condition que ce changement puisse \u00eatre pris en compte pour l\u2019examen auquel le candidat est inscrit.<\/p>\n<p>8.3 Si le changement de langue ne peut \u00eatre effectu\u00e9, les candidats auront le choix entre :<\/p>\n<p style=\"margin-left: 40px;\">8.3.1. se d\u00e9sinscrire de l&rsquo;examen sans frais ; ou<\/p>\n<p style=\"margin-left: 40px;\">8.3.2. passer l\u2019examen dans la langue initialement choisie.<\/p>\n<p>[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb9. Accommodements pour les examens\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Conditions d\u2019\u00e9ligibilit\u00e9<\/h5>\n<p>9.1 Les candidats peuvent demander un accommodement pour l\u2019examen (\u00ab Demande d\u2019accommodement pour l\u2019examen \u00bb) en <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/ressources\/accommodements-speciaux\/\" target=\"_blank\" rel=\"noopener\">raison d\u2019un handicap attest\u00e9, d\u2019un diagnostic m\u00e9dical ou pour des raisons religieuses<\/a>.<\/p>\n<h5>Dossiers<\/h5>\n<p>9.2 Sous r\u00e9serve du droit du BNED d\u2019exiger des informations suppl\u00e9mentaires, les exigences minimales d\u2019une demande d\u2019accommodements pour l\u2019examen sont les suivantes :<\/p>\n<p style=\"margin-left: 40px;\">9.2.1. un formulaire de demande d\u2019accommodements pour les examens rempli par le candidat et, le cas \u00e9ch\u00e9ant, par un professionnel de sant\u00e9 connaissant la situation du candidat ; et<\/p>\n<p style=\"margin-left: 40px;\">9.2.2. le cas \u00e9ch\u00e9ant, des pi\u00e8ces justificatives provenant :<\/p>\n<p style=\"margin-left: 80px;\">(a) d\u2019un professionnel de sant\u00e9 connaissant la situation du candidat, sous une forme acceptable pour le BNED ; ou<\/p>\n<p style=\"margin-left: 80px;\">(b) d\u2019un chef religieux, sous une forme acceptable pour le BNED.<\/p>\n<p style=\"margin-left: 40px;\">9.2.3. Le formulaire de demande d\u2019accommodements pour l\u2019examen et les pi\u00e8ces justificatives doivent \u00eatre soumis via NDEBConnect.<\/p>\n<p>9.3 Tout refus ou retard de r\u00e9ponse aux demandes d&rsquo;informations suppl\u00e9mentaires formul\u00e9es par le BNED peut entra\u00eener le rejet de la demande d&rsquo;accommodements du candidat.<\/p>\n<p>9.4 Pour les besoins d\u2019accommodements connus au moment de la demande d\u2019\u00eatre d\u00e9sign\u00e9 comme candidat \u00e0 la certification ou candidat \u00e0 l\u2019\u00e9quivalence, les candidats doivent soumettre une demande d\u2019accommodements imm\u00e9diatement apr\u00e8s leur inscription \u00e0 leur premier examen.<\/p>\n<p>9.5 En cas de besoin d\u2019accommodement nouveau ou modifi\u00e9 au cours du processus de certification ou d\u2019\u00e9quivalence, les candidats doivent soumettre une demande d\u2019accommodement pour l\u2019examen concern\u00e9 d\u00e8s que possible et au plus tard huit semaines avant la date de l\u2019examen.<\/p>\n<p>9.6 Le fait de ne pas soumettre de demande d\u2019accommodement au plus tard \u00e0 la date limite fix\u00e9e pour l\u2019examen concern\u00e9 peut entra\u00eener le rejet de la demande d\u2019accommodement du candidat.<\/p>\n<h5>Cons\u00e9quences<\/h5>\n<p>9.7 Apr\u00e8s examen d\u2019une demande d\u2019accommodement, le personnel du BNED peut :<\/p>\n<p style=\"margin-left: 40px;\">9.7.1. faire droit \u00e0 la demande d\u2019accommodements ;<\/p>\n<p style=\"margin-left: 40px;\">9.7.2. proposer un accommodement diff\u00e9rent de celui demand\u00e9 par le candidat ;<\/p>\n<p style=\"margin-left: 40px;\">9.7.3. rejeter la demande d&rsquo;accommodements ; ou<\/p>\n<p style=\"margin-left: 40px;\">9.7.4. demander au candidat de fournir des informations suppl\u00e9mentaires.<\/p>\n<p>9.8 Une fois la demande d\u2019accommodement accept\u00e9e ou l\u2019accommodement propos\u00e9 accept\u00e9, le BNED \u00e9laborera un plan d\u2019accommodement (le \u00ab Plan d\u2019accommodements \u00bb) pour le candidat. Le personnel du BNED communiquera ce plan d\u2019accommodement au candidat par courriel. \u00c0 la r\u00e9ception du plan d\u2019accommodement du BNED, le candidat peut, dans les d\u00e9lais fix\u00e9s par le BNED :<\/p>\n<p style=\"margin-left: 40px;\">9.8.1. accepter le Plan d\u2019accommodements ; ou<\/p>\n<p style=\"margin-left: 40px;\">9.8.2. refuser le Plan d\u2019accommodements.<\/p>\n<p>9.9 Si le candidat rejette le Plan d\u2019accommodements, il peut :<\/p>\n<p style=\"margin-left: 40px;\">9.9.1. passer l\u2019examen concern\u00e9 sans aucun accommodement ; ou<\/p>\n<p style=\"margin-left: 40px;\">9.9.2. se d\u00e9sister de l\u2019examen concern\u00e9.<\/p>\n<p>9.10 Un Plan d\u2019accommodements ne peut modifier la nature et le niveau des aptitudes ou des comp\u00e9tences \u00e9valu\u00e9es lors d\u2019un examen et ne peut constituer une modification fondamentale des exigences de l\u2019examen.<\/p>\n<p>9.11 Le BNED peut, \u00e0 sa seule discr\u00e9tion, d\u00e9terminer la date, le lieu et l\u2019heure de la session d\u2019un examen organis\u00e9 conform\u00e9ment \u00e0 un plan d\u2019accommodements.<\/p>\n<p>9.12 Le candidat est seul responsable des frais suppl\u00e9mentaires qu\u2019il pourrait engager du fait de l\u2019acceptation d\u2019un plan d\u2019accommodements.<\/p>\n<p>9.13 Un plan d\u2019accommodements est valable pour l\u2019inscription concern\u00e9e pour laquelle il a \u00e9t\u00e9 \u00e9tabli. Une nouvelle demande d\u2019accommodements doit \u00eatre soumise pour chaque inscription.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb10. D\u00e9sistement d\u2019un examen pour raisons m\u00e9dicales ou autres circonstances exceptionnelles impr\u00e9vues\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Conditions d\u2019\u00e9ligibilit\u00e9<\/h5>\n<p>10.1 Les candidats inscrits \u00e0 un examen et confront\u00e9s \u00e0 des circonstances exceptionnelles impr\u00e9vues, y compris une situation m\u00e9dicale exceptionnelle, avant la date de l\u2019examen doivent se d\u00e9sister et soumettre une demande de remboursement d\u2019une partie des droits d\u2019examen (une \u00ab demande de remboursement \u00bb).<\/p>\n<p><strong>Soumissions des demandes<\/strong><\/p>\n<p>10.2 Le BNED ne prendra en compte que les demandes de remboursement compl\u00e8tes, comprenant toutes les informations requises. Sous r\u00e9serve du droit du BNED de demander des informations suppl\u00e9mentaires, les conditions minimales requises pour une demande de remboursement sont les suivantes :<\/p>\n<p style=\"margin-left: 40px;\">10.2.1. Le candidat doit s&rsquo;\u00eatre d\u00e9sinscrit de l&rsquo;examen sur NDEBConnect avant le d\u00e9but de celui-ci et indiquer le motif de sa d\u00e9sinscription.<\/p>\n<p style=\"margin-left: 40px;\">10.2.2. la demande de remboursement doit \u00eatre envoy\u00e9e par courriel au bureau du BNED dans les sept (7) jours suivant le d\u00e9sistement et pr\u00e9ciser la circonstance exceptionnelle et impr\u00e9vue justifiant ce d\u00e9sistement ; et<\/p>\n<p style=\"margin-left: 40px;\">10.2.3. la demande de remboursement doit \u00eatre accompagn\u00e9e d\u2019un certificat m\u00e9dical, en cas de circonstance m\u00e9dicale exceptionnelle, ou de tout autre justificatif, en cas d\u2019autre circonstance exceptionnelle impr\u00e9vue.<\/p>\n<p><strong>Cons\u00e9quences<\/strong><\/p>\n<p>10.3 Apr\u00e8s examen de la demande de remboursement, le personnel du BNED peut :<\/p>\n<p style=\"margin-left: 40px;\">10.3.1. accorder la demande de remboursement et d\u00e9terminer le montant appropri\u00e9 ; ou<\/p>\n<p style=\"margin-left: 40px;\">10.3.2. conclure que la demande de remboursement ne r\u00e9pond pas aux exigences \u00e9nonc\u00e9es \u00e0 la section 10.2 et rejeter la demande de remboursement.<\/p>\n<p>10.4 Le personnel du BNED communiquera sa d\u00e9cision concernant la demande de remboursement au candidat par courriel.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb11. Actes interdits\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Admissibilit\u00e9<\/h5>\n<p>11.1 Les candidats sont tenus de se conformer aux dispositions \u00e9nonc\u00e9es dans le protocole d\u2019examen applicable ainsi qu\u2019\u00e0 toutes les r\u00e8gles r\u00e9gissant le lieu d\u2019examen. Toute violation des protocoles d\u2019examen ou des r\u00e8gles r\u00e9gissant le lieu d\u2019examen est consid\u00e9r\u00e9e comme une action interdite pouvant faire l\u2019objet d\u2019une enqu\u00eate men\u00e9e par le registraire.<\/p>\n<p><strong>Cons\u00e9quences<\/strong><\/p>\n<p>11.2 \u00c0 l\u2019issue d\u2019une enqu\u00eate sur une violation potentielle des protocoles d\u2019examen ou des r\u00e8gles r\u00e9gissant le lieu d\u2019examen, consid\u00e9r\u00e9e comme une action interdite, le registraire doit :<\/p>\n<p style=\"margin-left: 40px;\">11.2.1. cl\u00f4turer l\u2019enqu\u00eate ; ou<\/p>\n<p style=\"margin-left: 40px;\">11.2.2. conclure qu\u2019un candidat s\u2019est rendu coupable d\u2019un acte interdit et imposer les sanctions appropri\u00e9es, qui peuvent inclure, sans s\u2019y limiter :<\/p>\n<p style=\"margin-left: 80px;\">(a) suspendre ou r\u00e9silier l\u2019acc\u00e8s au syst\u00e8me d\u2019inscription ;<\/p>\n<p style=\"margin-left: 80px;\">(b) annuler une inscription \u00e0 un examen ;<\/p>\n<p style=\"margin-left: 80px;\">(c) suspendre le droit de s\u2019inscrire \u00e0 un examen jusqu\u2019\u00e0 une date d\u00e9termin\u00e9e ou apr\u00e8s celle-ci ;<\/p>\n<p style=\"margin-left: 80px;\">(d) annuler le ou les r\u00e9sultats d\u2019examen ;<\/p>\n<p style=\"margin-left: 80px;\">(e) attribuer la note z\u00e9ro ou \u00ab \u00e9chec \u00bb \u00e0 l&rsquo;une ou \u00e0 l&rsquo;ensemble des questions ou des exigences d&rsquo;un examen ;<\/p>\n<p style=\"margin-left: 80px;\">(f) interdire au candidat de passer des examens \u00e0 l&rsquo;avenir ;<\/p>\n<p style=\"margin-left: 80px;\">(g) engager des poursuites judiciaires \u00e0 l\u2019encontre de toute personne ayant compromis la s\u00e9curit\u00e9 de l\u2019examen ; ou<\/p>\n<p style=\"margin-left: 80px;\">(h) d&rsquo;autres sanctions jug\u00e9es appropri\u00e9es au vu des circonstances.<\/p>\n<p>[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>IV. Appels<\/h3>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_accordion active_tab=\u00a0\u00bb\u00a0\u00bb collapsible=\u00a0\u00bbyes\u00a0\u00bb style=\u00a0\u00bbaccordion\u00a0\u00bb][vc_accordion_tab title=\u00a0\u00bb12. Appel relatif \u00e0 la conduite d\u2019un examen\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Soumissions des demandes<\/h5>\n<p>12.1 Le Comit\u00e9 d\u2019appel n\u2019examinera qu\u2019un appel relatif \u00e0 la conduite d\u2019un examen qui soit complet et comprenne toutes les informations requises. Sous r\u00e9serve du droit du BNED d\u2019exiger des informations suppl\u00e9mentaires, les exigences minimales relatives \u00e0 l\u2019appel relatif \u00e0 la conduite d\u2019un examen (un \u00ab appel concernant la conduite d\u2019un examen \u00bb) sont les suivantes :<\/p>\n<p style=\"margin-left: 40px;\">12.1.1. le soumission de l\u2019appel relatif \u00e0 la conduite d\u2019un examen via NDEBConnect dans un d\u00e9lai de sept (7) jours \u00e0 compter de la date de l\u2019examen concern\u00e9 ;<\/p>\n<p style=\"margin-left: 40px;\">12.1.2. le paiement int\u00e9gral des droits de dossier correspondants au moment du soumission de l\u2019appel concernant la tenue d\u2019un examen;<\/p>\n<p style=\"margin-left: 40px;\">12.1.3. une description du probl\u00e8me majeur li\u00e9 \u00e0 l\u2019administration de l\u2019examen rencontr\u00e9 par le candidat ;<\/p>\n<p style=\"margin-left: 40px;\">12.1.4. la confirmation que le candidat a signal\u00e9 le probl\u00e8me au personnel pr\u00e9sent sur place pendant l\u2019examen ; et<\/p>\n<p style=\"margin-left: 40px;\">12.1.5. des informations indiquant si et comment le probl\u00e8me a \u00e9t\u00e9 trait\u00e9, et, s\u2019il n\u2019a pas \u00e9t\u00e9 trait\u00e9 de mani\u00e8re ad\u00e9quate, en quoi cela a emp\u00each\u00e9 le candidat de d\u00e9montrer ses comp\u00e9tences lors de l\u2019examen.<\/p>\n<p>12.2 Si le candidat d\u00e9pose un appel concernant la conduite d\u2019un examen mais obtient par la suite une note suffisante \u00e0 l\u2019examen concern\u00e9, le personnel du BNED l\u2019informera par courriel que son recours est rejet\u00e9. Les droits de d\u00e9p\u00f4t de dossier ne seront pas rembours\u00e9s.<\/p>\n<h5>Cons\u00e9quences<\/h5>\n<p>12.3 Apr\u00e8s examen, si le registraire d\u00e9termine que les irr\u00e9gularit\u00e9s ou incoh\u00e9rences n\u2019ont pas pu avoir d\u2019incidence sur les r\u00e9sultats du candidat \u00e0 l\u2019examen, l\u2019appel concernant la conduite ne sera pas renvoy\u00e9 devant un panel de membres du Comit\u00e9 d\u2019appel (le \u00abPanel\u00bb). La note d\u2019\u00e9chec du candidat sera valid\u00e9e et les droits de d\u00e9p\u00f4t de dossier ne seront pas rembours\u00e9s.<\/p>\n<p>12.4 Si, apr\u00e8s examen, le registraire estime que des irr\u00e9gularit\u00e9s ou des incoh\u00e9rences ont pu avoir une incidence sur les r\u00e9sultats du candidat \u00e0 l\u2019examen, l\u2019appel concernant la conduite d\u2019un examen sera examin\u00e9 par le Panel, accompagn\u00e9 des documents pertinents relatifs \u00e0 l\u2019examen.<\/p>\n<p>12.5 Apr\u00e8s examen de l\u2019appel concernant la conduite d\u2019examen, le Panel peut :<\/p>\n<p style=\"margin-left: 40px;\">12.5.1. faire droit au recours pour faute de conduite en tout ou en partie et accorder toute autre mesure de r\u00e9paration en plus ou \u00e0 la place de celle demand\u00e9e ; ou<\/p>\n<p style=\"margin-left: 40px;\">12.5.2. rejeter le recours en mati\u00e8re de discipline.<\/p>\n<p>12.6 La d\u00e9cision du Panel d\u2019accepter ou de rejeter un appel concernant la conduite d\u2019un examen est d\u00e9finitive.<\/p>\n<p>12.7 Le personnel du BNED communiquera la d\u00e9cision de la commission au candidat par courriel.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb13. Appel de compassion\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Admissibilit\u00e9<\/h5>\n<p>13.1 Les candidats qui, lors d\u2019un examen, ont \u00e9t\u00e9 confront\u00e9s \u00e0 une circonstance exceptionnelle et impr\u00e9vue, ind\u00e9pendante de leur volont\u00e9, les ayant emp\u00each\u00e9s de d\u00e9montrer leurs capacit\u00e9s, peuvent d\u00e9poser un Appel de compassion aupr\u00e8s du BNED (l\u2019 \u00ab Appel de compassion \u00bb) si toutes les conditions suivantes sont remplies :<\/p>\n<p style=\"margin-left: 40px;\">13.1.1. le candidat n\u2019a pas termin\u00e9 l\u2019examen ;<\/p>\n<p style=\"margin-left: 40px;\">13.1.2. le candidat a inform\u00e9 le personnel sur place, au moment de son d\u00e9part, qu\u2019il n\u2019\u00e9tait pas en mesure de terminer l\u2019examen en raison de circonstances exceptionnelles et impr\u00e9vues ind\u00e9pendantes de sa volont\u00e9 ; et<\/p>\n<p style=\"margin-left: 40px;\">13.1.3. le personnel sur place doit avoir r\u00e9dig\u00e9 un rapport indiquant l\u2019heure \u00e0 laquelle le candidat a quitt\u00e9 la salle d\u2019examen.<\/p>\n<h5>Soumissions des demandes<\/h5>\n<p>13.2 Le Comit\u00e9 ex\u00e9cutif n\u2019examinera que les appels de compassion complets comprenant toutes les informations requises. Sous r\u00e9serve du droit du BNED d\u2019exiger des informations suppl\u00e9mentaires, les exigences minimales d\u2019un appel de compassion sont les suivantes :<\/p>\n<p style=\"margin-left: 40px;\">13.2.1. le soumission de l\u2019Appel de compassion via NDEBConnect dans les sept (7) jours suivant la date de l\u2019examen concern\u00e9, laquelle doit :<\/p>\n<p style=\"margin-left: 80px;\">(a) d\u00e9crire la circonstance exceptionnelle et impr\u00e9vue, ind\u00e9pendante de sa volont\u00e9, \u00e0 laquelle le candidat a \u00e9t\u00e9 confront\u00e9 pendant l\u2019examen ;<\/p>\n<p style=\"margin-left: 80px;\">(b) confirmer que le candidat a signal\u00e9 au personnel pr\u00e9sent sur place pendant l\u2019examen qu\u2019il n\u2019\u00e9tait pas en mesure de terminer l\u2019examen en raison de circonstances exceptionnelles et impr\u00e9vues ind\u00e9pendantes de sa volont\u00e9 ; et<\/p>\n<p style=\"margin-left: 80px;\">(c) confirmer qu\u2019en raison de ces circonstances exceptionnelles et impr\u00e9vues, le candidat a quitt\u00e9 l\u2019examen sans l\u2019avoir termin\u00e9.<\/p>\n<p style=\"margin-left: 40px;\">13.2.2. la soumission d\u2019informations relatives \u00e0 des circonstances familiales ou de documents m\u00e9dicaux via NDEBConnect dans un d\u00e9lai de sept (7) jours \u00e0 compter de la date de l\u2019examen concern\u00e9.<\/p>\n<h5>Cons\u00e9quences<\/h5>\n<p>13.3 Le personnel du BNED v\u00e9rifiera que l\u2019Appel de compassion r\u00e9pond aux exigences minimales \u00e9nonc\u00e9es \u00e0 la section 13.2. Seules les demandes d\u2019Appel de compassion qui respectent les exigences minimales \u00e9nonc\u00e9es \u00e0 la section 13.2 seront examin\u00e9es par le Comit\u00e9 ex\u00e9cutif.<\/p>\n<p>13.4 Le personnel du BNED informera le candidat par courriel du r\u00e9sultat de sa v\u00e9rification.<\/p>\n<p>13.5 Apr\u00e8s examen d\u2019un Appel de compassion, le Comit\u00e9 ex\u00e9cutif peut :<\/p>\n<p style=\"margin-left: 40px;\">13.5.1. faire droit \u00e0 l\u2019Appel de compassion en tout ou en partie et accorder toute autre mesure de redressement en plus ou \u00e0 la place de celle demand\u00e9e, y compris, sans s\u2019y limiter, le remboursement des droits ; ou<\/p>\n<p style=\"margin-left: 40px;\">13.5.2. rejeter l\u2019Appel de compassion.<\/p>\n<p>13.6 La d\u00e9cision du Comit\u00e9 ex\u00e9cutif d\u2019accorder ou de rejeter un Appel de compassion est d\u00e9finitive.<\/p>\n<p>13.7 Le personnel du BNED communiquera la d\u00e9cision du Comit\u00e9 ex\u00e9cutif au candidat par courriel.<\/p>\n<p>13.8 En cas d\u2019acceptation de l\u2019Appel de compassion, le r\u00e9sultat de l\u2019examen du candidat sera annul\u00e9.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb14. V\u00e9rification des notes\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>Admissibilit\u00e9<\/h5>\n<p>14.1 Les candidats ayant \u00e9chou\u00e9 \u00e0 un examen peuvent soumettre une demande de v\u00e9rification de leur note (\u00ab Demande de v\u00e9rification \u00bb).<\/p>\n<h5>Soumissions des demandes<\/h5>\n<p>14.2 La demande de v\u00e9rification d&rsquo;un candidat doit respecter les exigences minimales suivantes :<\/p>\n<p style=\"margin-left: 40px;\">14.2.1. la demande de v\u00e9rification doit \u00eatre soumise via NDEBConnect dans les trente (30) jours suivant la date de publication des r\u00e9sultats de l&rsquo;examen concern\u00e9 ; et<\/p>\n<p style=\"margin-left: 40px;\">14.2.2. la demande de v\u00e9rification doit \u00eatre accompagn\u00e9e des droits correspondants, pay\u00e9s int\u00e9gralement au moment du soumission de la demande.<\/p>\n<h5>Cons\u00e9quences<\/h5>\n<p>14.3 D\u00e8s r\u00e9ception d\u2019une demande de v\u00e9rification, le personnel du BNED v\u00e9rifiera le r\u00e9sultat de l\u2019examen. Le personnel du BNED enverra les r\u00e9sultats de la v\u00e9rification par courriel dans un d\u00e9lai d\u2019environ six (6) semaines \u00e0 compter de la demande de v\u00e9rification.<\/p>\n<p>14.4 Si, \u00e0 l\u2019issue de la v\u00e9rification, le candidat obtient un r\u00e9sultat positif, toute inscription existante pour le m\u00eame examen sera annul\u00e9e et les droits d\u2019examen rembours\u00e9s.<\/p>\n<p>14.5 La note d\u2019examen du candidat apr\u00e8s v\u00e9rification est d\u00e9finitive.<\/p>\n<p>14.6 Le BNED ne fournira pas au candidat l\u2019examen concern\u00e9, le corrig\u00e9 de cet examen ni sa feuille de r\u00e9sultats, que ce soit \u00e0 la suite d\u2019une demande de v\u00e9rification ou dans toute autre circonstance.[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>V. D\u00e9claration fausse ou trompeuse<\/h3>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_accordion active_tab=\u00a0\u00bb\u00a0\u00bb collapsible=\u00a0\u00bbyes\u00a0\u00bb style=\u00a0\u00bbaccordion\u00a0\u00bb][vc_accordion_tab title=\u00a0\u00bb15. D\u00e9finition\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]15.1 Une d\u00e9claration fausse ou trompeuse au sens de l\u2019article 5 du r\u00e8glement n\u00b0 2 d\u00e9signe :<\/p>\n<p style=\"margin-left: 40px;\">15.1.1. le fait d\u2019inclure des informations ou des documents falsifi\u00e9s dans la demande d\u2019une personne visant \u00e0 devenir candidat \u00e0 la certification ou candidat \u00e0 l\u2019\u00e9quivalence ;<\/p>\n<p style=\"margin-left: 40px;\">15.1.2. Une violation de :<\/p>\n<p style=\"margin-left: 80px;\">(a) conditions g\u00e9n\u00e9rales relatives aux soumissions en ligne ;<\/p>\n<p style=\"margin-left: 80px;\">(b) l\u2019Accord de confidentialit\u00e9 et de reconnaissance de la propri\u00e9t\u00e9 intellectuelle ; ou<\/p>\n<p style=\"margin-left: 80px;\">(c) l\u2019accord de confidentialit\u00e9 et de non-divulgation de l\u2019EDNCC.<\/p>\n<p>[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb16. Appels contre les mesures administratives\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h5>\u00c9ligibilit\u00e9<\/h5>\n<p>16.1 Toute personne faisant l\u2019objet de mesures administratives d\u00e9termin\u00e9es par le registraire conform\u00e9ment \u00e0 l\u2019article 5.3 du r\u00e8glement n\u00b0 2 peut introduire un recours contre ces mesures administratives.<\/p>\n<p>16.2 Les motifs de recours se limitent \u00e0 toute mesure administrative suppl\u00e9mentaire impos\u00e9e par le registraire conform\u00e9ment \u00e0 l\u2019article 5.3.<\/p>\n<p>16.3 Soumissions des demandes Le Comit\u00e9 d\u2019appel n\u2019examinera qu\u2019un recours contre les mesures administratives complet comprenant toutes les informations requises. Sous r\u00e9serve du droit du BNED d\u2019exiger des informations suppl\u00e9mentaires, les exigences minimales d\u2019un recours contre les mesures administratives sont les suivantes :<\/p>\n<p style=\"margin-left: 40px;\">16.3.1. le soumission de l\u2019appel contre les mesures administratives via NDEBConnect dans un d\u00e9lai de dix (10) jours ouvrables \u00e0 compter de la r\u00e9ception par la personne concern\u00e9e de la d\u00e9cision du le registraire relative aux mesures administratives, conform\u00e9ment \u00e0 l\u2019article 5.4 du r\u00e8glement n\u00b0 2 ;<\/p>\n<p style=\"margin-left: 40px;\">16.3.2. le paiement int\u00e9gral des droits de d\u00e9p\u00f4t correspondants au moment du soumission de l\u2019appel des mesures administratives ; et<\/p>\n<p style=\"margin-left: 40px;\">16.3.3. des copies de toute pi\u00e8ce justificative mentionn\u00e9e ou invoqu\u00e9e par la personne dans son recours contre des mesures administratives.<\/p>\n<h5>Cons\u00e9quences<\/h5>\n<p>16.4 Apr\u00e8s examen du recours contre les mesures administratives et conform\u00e9ment \u00e0 l\u2019article 5 du r\u00e8glement n\u00b0 2, la Comit\u00e9 d\u2019appel peut :<\/p>\n<p style=\"margin-left: 40px;\">16.4.1. faire droit au recours contre les mesures administratives, en tout ou en partie, et accorder toute autre mesure de redressement en plus ou \u00e0 la place de celle demand\u00e9e ; ou<\/p>\n<p style=\"margin-left: 40px;\">16.4.2. rejeter le recours contre les mesures administratives.<\/p>\n<p>16.5 La d\u00e9cision du Comit\u00e9 d\u2019appel d\u2019accorder ou de rejeter un recours contre des mesures administratives est d\u00e9finitive.<\/p>\n<p>16.6 Le personnel du BNED communiquera la d\u00e9cision du comit\u00e9 d\u2019appel \u00e0 la personne concern\u00e9e par courriel.[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>VI. Documentation relative aux soins de sant\u00e9<\/h3>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_accordion active_tab=\u00a0\u00bb\u00a0\u00bb collapsible=\u00a0\u00bbyes\u00a0\u00bb style=\u00a0\u00bbaccordion\u00a0\u00bb][vc_accordion_tab title=\u00a0\u00bb17. Exigences relatives \u00e0 la documentation des soins de sant\u00e9\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]17.1 Le BNED n&rsquo;acceptera que les documents m\u00e9dicaux r\u00e9pondant \u00e0 l&rsquo;ensemble des crit\u00e8res suivants :<\/p>\n<p style=\"margin-left: 40px;\">17.1.1. \u00eatre d\u00e9livr\u00e9s au moment de la maladie ou de l\u2019accident ;<\/p>\n<p style=\"margin-left: 40px;\">17.1.2. \u00eatre d\u00e9livr\u00e9s par un professionnel de sant\u00e9 ;<\/p>\n<p style=\"margin-left: 40px;\">17.1.3. \u00eatre r\u00e9dig\u00e9s sur du papier \u00e0 en-t\u00eate officiel du cabinet ou de l\u2019h\u00f4pital ;<\/p>\n<p style=\"margin-left: 40px;\">17.1.4. mentionner les qualifications et les coordonn\u00e9es du professionnel de sant\u00e9 ;<\/p>\n<p style=\"margin-left: 40px;\">17.1.5. comporter un diagnostic clair et une description des limitations associ\u00e9es \u00e0 ce diagnostic ;<\/p>\n<p style=\"margin-left: 40px;\">17.1.6. indiquer clairement que le candidat n\u2019est pas apte \u00e0 passer l\u2019examen ;<\/p>\n<p style=\"margin-left: 40px;\">17.1.7. indiquer une date de r\u00e9tablissement pr\u00e9vue ; et<\/p>\n<p style=\"margin-left: 40px;\">17.1.8. \u00eatre r\u00e9dig\u00e9 en anglais ou en fran\u00e7ais.<\/p>\n<p>[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb18. V\u00e9rification des documents m\u00e9dicaux\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]18.1 Tous les candidats qui soumettent des documents m\u00e9dicaux doivent \u00e9galement donner leur consentement au BNED pour qu\u2019il puisse contacter le professionnel de sant\u00e9 \u00e9metteur afin de v\u00e9rifier les documents m\u00e9dicaux fournis.<\/p>\n<p>18.2 Ce consentement devra \u00eatre fourni sous une forme et dans des termes acceptables tant pour le BNED que pour le professionnel de sant\u00e9.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=\u00a0\u00bb19. Documents non acceptables\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]19.1 Le BNED n\u2019acceptera aucun des documents suivants comme justificatifs m\u00e9dicaux :<\/p>\n<p style=\"margin-left: 40px;\">19.1.1. les lettres manuscrites r\u00e9dig\u00e9es par des professionnels de sant\u00e9 ;<\/p>\n<p style=\"margin-left: 40px;\">19.1.2. les dossiers m\u00e9dicaux manuscrits ou les notes tir\u00e9es des dossiers des patients ;<\/p>\n<p style=\"margin-left: 40px;\">19.1.3. les diagnostics figurant sur des ordonnanciers ;<\/p>\n<p style=\"margin-left: 40px;\">19.1.4. les diagnostics fond\u00e9s sur des d\u00e9clarations des patients eux-m\u00eames ; ou<\/p>\n<p style=\"margin-left: 40px;\">19.1.5. des articles de recherche.<\/p>\n<p>[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text]T\u00e9l\u00e9chargez le document \u00ab <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/wp-content\/uploads\/2026\/07\/2026-07-10-Politiques-des-examens-et-appels.pdf\" target=\"_blank\" rel=\"noopener\">Politiques et proc\u00e9dures relatives aux examens et aux appels<\/a> \u00bb[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1743795465144{padding-top: 90px !important;padding-bottom: 0px !important;}\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbflex-box\u00a0\u00bb background_color=\u00a0\u00bb#F2F1F1&Prime;][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb] R\u00e8glements du BNED Les R\u00e8glements du BNED r\u00e9gissent le fonctionnement de l\u2019organisation,&#8230;<\/p>\n","protected":false},"author":46,"featured_media":0,"parent":917,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-99263","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/99263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=99263"}],"version-history":[{"count":21,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/99263\/revisions"}],"predecessor-version":[{"id":99436,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/99263\/revisions\/99436"}],"up":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/917"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=99263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}