{"id":5207,"date":"2022-01-17T11:51:55","date_gmt":"2022-01-17T16:51:55","guid":{"rendered":"https:\/\/ndeb-bned.ca\/activity-log-backup\/?page_id=5207"},"modified":"2026-04-16T07:33:56","modified_gmt":"2026-04-16T11:33:56","slug":"processus-dequivalence-nouvelle-demande","status":"publish","type":"page","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/ressources\/processus-dequivalence-nouvelle-demande\/","title":{"rendered":"Processus d&rsquo;\u00e9quivalence: Nouvelle demande"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column]<div class=\"call_to_action with_icon\" style=\"\"><div class=\"container_inner\"><div class=\"text_wrapper \"><div class=\"call_to_action_icon_holder\"><div class=\"call_to_action_icon\"><div class=\"call_to_action_icon_inner\"><i class='fa fa-exclamation-circle pull-left . fa-2x' style='color: #ffffff;'><\/i><\/div><\/div><\/div><div class=\"call_to_action_text \" style=\"\">\n<h2 class=\"h3\">Avis sp\u00e9cial<\/h2>\n<p>\u00c0 compter du 1er mai 2027, il ne sera plus possible de pr\u00e9senter une nouvelle demande dans le cadre de la Processus d&rsquo;\u00e9quivalence.<\/div><\/div><\/div><\/div>[vc_empty_space][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Les candidats qui ont \u00e9chou\u00e9 trois fois \u00e0 l&rsquo;\u00e9valuation des comp\u00e9tences cliniques (ECC) peuvent se r\u00e9inscrire au Processus d&rsquo;\u00e9quivalence. Pour se r\u00e9inscrire, il faut remplir le formulaire de r\u00e9inscription et soumettre les documents requis suivants qui r\u00e9pondent aux exigences \u00e9nonc\u00e9es dans le guide de candidature :<\/p>\n<ul>\n<li>Formulaire de documents requis pour le processus d&rsquo;\u00e9quivalence, sign\u00e9 et dat\u00e9.<\/li>\n<li>Une photocopie notari\u00e9e de l&rsquo;une des pi\u00e8ces d&rsquo;identit\u00e9 avec photo d\u00e9livr\u00e9es par le gouvernement.<\/li>\n<li>Une lettre ou un certificat d\u00e9livr\u00e9 par tous les organismes d&rsquo;agr\u00e9ment dans lesquels vous avez \u00e9t\u00e9 agr\u00e9\u00e9, confirmant que vous \u00eates ou \u00e9tiez autoris\u00e9 \u00e0 exercer dans la juridiction, que vous n&rsquo;avez pas \u00e9t\u00e9 disqualifi\u00e9, suspendu ou interdit d&rsquo;exercer, et que l&rsquo;organisme de r\u00e9glementation n&rsquo;a pas connaissance d&rsquo;\u00e9l\u00e9ments remettant en cause votre bonne r\u00e9putation, votre aptitude \u00e0 exercer ou votre \u00ab bonne moralit\u00e9 \u00bb en tant que professionnel de la sant\u00e9.<\/li>\n<\/ul>\n<p>Document facultatif :<\/p>\n<p>Si vous \u00eates r\u00e9sident canadien et que vous souhaitez fournir une preuve de votre r\u00e9sidence, vous pouvez soumettre une photocopie notari\u00e9e de l&rsquo;un des documents \u00e9num\u00e9r\u00e9s dans le guide de candidature. Cette preuve n&rsquo;est pas n\u00e9cessaire pour passer l&rsquo;examen du BNED.<\/p>\n<p>Une fois que votre demande a \u00e9t\u00e9 re\u00e7ue, vous devrez payer les frais de r\u00e9inscription non remboursables de 400 $ par l&rsquo;interm\u00e9diaire de votre compte NDEBConnect. Des documents suppl\u00e9mentaires peuvent \u00eatre demand\u00e9s afin de v\u00e9rifier l&rsquo;admissibilit\u00e9 au processus d&rsquo;\u00e9quivalence du BNED.[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h3>Formulaire de r\u00e9-application: Processus d&rsquo;\u00e9quivalence<\/h3>\n<p><link rel='stylesheet' id='formidable-css' href='https:\/\/ndeb-bned.ca\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=8301549' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_center_submit frm_style_ndeb-form-style\" id=\"frm_form_13_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form48f76f6bbbca7cc4b2781e42a8d444\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">R\u00e9application : Processus d'\u00e9quivalence du BNED<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"13\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_13\" id=\"frm_hide_fields_13\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form48f76f6bbbca7cc4b2781e42a8d444\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_13\" name=\"frm_submit_entry_13\" value=\"2343c6232f\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/5207\" \/><div id=\"frm_field_434_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm4 frm_first\">\r\n    <label for=\"field_e6lis682ec40a885318d600696a981b11c66\" id=\"field_e6lis682ec40a885318d600696a981b11c66_label\" class=\"frm_primary_label\">Nom de famille\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_e6lis682ec40a885318d600696a981b11c66\" name=\"item_meta[434]\" value=\"\"  data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" aria-required=\"true\" data-invmsg=\"L&#039;objet n&#039;est pas valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_447_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm4\">\r\n    <label for=\"field_q05e1\" id=\"field_q05e1_label\" class=\"frm_primary_label\">Pr\u00e9nom\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_q05e1\" name=\"item_meta[447]\" value=\"\"  data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" aria-required=\"true\" data-invmsg=\"L&#039;objet n&#039;est pas valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_435_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm4\">\r\n    <label for=\"field_qh4icy5f8f1adf17e7867981d4e52ddbdf45\" id=\"field_qh4icy5f8f1adf17e7867981d4e52ddbdf45_label\" class=\"frm_primary_label\">Num\u00e9ro d'identification du BNED\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy5f8f1adf17e7867981d4e52ddbdf45\" name=\"item_meta[435]\" value=\"\"  data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" aria-required=\"true\" data-invmsg=\"Le nom n&#039;est pas valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_438_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12  frm6 frm_third frm_first\">\r\n    <label for=\"field_i8fyl1a1f56b770cbd990877a\" id=\"field_i8fyl1a1f56b770cbd990877a_label\" class=\"frm_primary_label\">Date de naissance (mm\/jj\/aaaa)\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_i8fyl1a1f56b770cbd990877a\" name=\"item_meta[438]\" value=\"\"  maxlength=\"10\" data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" aria-required=\"true\" data-invmsg=\"La date n&#039;est pas valide\" class=\"frm_date\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_436_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_third frm_two_thirds\">\r\n    <label for=\"field_29yf4d3644d68fd326f39b9e2e54316087ba\" id=\"field_29yf4d3644d68fd326f39b9e2e54316087ba_label\" class=\"frm_primary_label\">Adresse courriel\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_29yf4d3644d68fd326f39b9e2e54316087ba\" name=\"item_meta[436]\" value=\"\"  data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" aria-required=\"true\" data-invmsg=\"S&#039;il vous pla\u00eet, mettez une adresse email valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_448_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n    <label for=\"field_2nc7p\" id=\"field_2nc7p_label\" class=\"frm_primary_label\">Nom de l'Universit\u00e9 sur le dipl\u00f4me\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_2nc7p\" name=\"item_meta[448]\" value=\"\"  data-reqmsg=\"Nom de l&#039;Universit\u00e9 sur le dipl\u00f4me cannot be blank.\" aria-required=\"true\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_449_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_half\">\r\n    <label for=\"field_uwxrt\" id=\"field_uwxrt_label\" class=\"frm_primary_label\">Date de remise du dipl\u00f4me\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_uwxrt\" name=\"item_meta[449]\" value=\"\"  data-reqmsg=\"Date de remise du dipl\u00f4me cannot be blank.\" aria-required=\"true\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_440_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12\">\r\n    <label for=\"field_xwwr3171a498dd7\" id=\"field_xwwr3171a498dd7_label\" class=\"frm_primary_label\">Joignez une coie d'une pi\u00e8ce d'identit\u00e9 actuelle avec photo d\u00e9ivr\u00e9e par le gouvernement\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"hidden\"  data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" data-invmsg=\"Le t\u00e9l\u00e9chargement de fichier n&#039;est pas valide\" aria-invalid=\"false\"   name=\"item_meta[440][]\"  data-reqmsg=\"Ce champ ne peut \u00eatre vide.\"  value=\"\" data-frmfile=\"440\" \/>\n\n<div class=\"frm_dropzone frm_multi_upload frm_clearfix\" id=\"file440_dropzone\" role=\"group\" >\n\t<div class=\"fallback\">\n\t\t<input type=\"file\" name=\"file440[]\" id=\"field_xwwr3171a498dd7\"\n\t\t\t data-frmfile=\"440\" multiple=\"multiple\"  data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" data-invmsg=\"Le t\u00e9l\u00e9chargement de fichier n&#039;est pas valide\" aria-invalid=\"false\"  \t\t\t\/>\n\t\t\t\t<div class=\"frm_clearfix \"><\/div>\n\t<\/div>\n\t<div class=\"dz-message needsclick\">\n\t\t\t\t<svg  viewBox=\"0 0 18 18\" class=\"frmsvg frm-svg-icon\">\n\t<path viewBox=\"0 0 18 18\" fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.2 4v8a.8.8 0 001.5 0V4l2.1 2.2A.7.7 0 1013 5L9.5 1.7a.7.7 0 00-1.1 0L5.1 5.2a.8.8 0 001 1l2.1-2zm7.6 4.3c.4 0 .7.3.7.7v6.8c0 .4-.3.7-.8.7H2.3a.8.8 0 01-.8-.8V9A.8.8 0 013 9v6h12V9c0-.4.3-.8.8-.8z\"><\/path>\n<\/svg>\t\t<span class=\"frm_upload_text\"><button type=\"button\" aria-label=\"Joignez une coie d&#039;une pi\u00e8ce d&#039;identit\u00e9 actuelle avec photo d\u00e9ivr\u00e9e par le gouvernement. D\u00e9posez un fichier ici ou cliquez pour t\u00e9l\u00e9charger. Taille de fichier maximale\u00a0: 134.22MB\">D\u00e9posez un fichier ici ou cliquez pour t\u00e9l\u00e9charger<\/button><\/span>\n\t\t<span class=\"frm_compact_text\"><button type=\"button\" aria-label=\"Joignez une coie d&#039;une pi\u00e8ce d&#039;identit\u00e9 actuelle avec photo d\u00e9ivr\u00e9e par le gouvernement. Choisir le fichier. Taille de fichier maximale\u00a0: 134.22MB\">Choisir le fichier<\/button><\/span>\n\t\t<div class=\"frm_small_text\">\n\t\t\t<p>Taille de fichier maximale\u00a0: 134.22MB<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_441_container\" class=\"frm_form_field frm_section_heading form-field \">\r\n<h2 class=\"h3 frm_pos_top frm_section_spacing\">Autorisation et d\u00e9claration <\/h2>\r\n\r\n\r\n<div id=\"frm_field_442_container\" class=\"frm_form_field  mg-btm frm_html_container form-field\">Je d\u00e9clare que les informations et tous les documents justificatifs que j\u2019ai fournis sont, \u00e0 ma connaissance, v\u00e9ridiques, exacts et complets, et je comprends qu\u2019une d\u00e9claration fausse ou trompeuse pourrait avoir comme cons\u00e9quence une all\u00e9gation d'inconduite.<\/div>\n<\/div>\n<div id=\"frm_field_444_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_58ua8d04a8d538effbf780014\" id=\"field_58ua8d04a8d538effbf780014_label\" class=\"frm_primary_label\">Signature\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t\t<input  type=\"hidden\" name=\"item_meta[444][delete_saved_image]\" value=\"0\" \/>\n\t\t\t\t\t\t<input  type=\"hidden\" name=\"item_meta[444][content]\" value=\"\" \/>\n\t\t\t<div class=\"sigPad\" id='sigPad444' style=\"max-width:400px;\">\n\t<div class=\"sig sigWrapper\" style=\"height:150px;border-color:#d1d1d1;--bg-color:#ffffff;--active:#579AF6;--inactive:#eaeaea;--active-text:#ffffff;--inactive-text:#3f4b5b;--button-margin:22px;--button-size:20px;--button-padding:10px;--button-side-margin:22px;--icon:20px\">\n\n\t\t<ul class=\"sigNav\">\n\t\t\t\t<li class=\"drawIt\">\n\t\t\t\t\t<a href=\"#\" class=\"frm-active-sig-type\" title=\"Dessine le\" aria-label=\"Dessine le\">\n\t\t\t\t\t\t<svg  viewBox=\"0 0 22 20\" class=\"frmsvg\">\n\t<title>signature<\/title>\n\t<path d=\"M19.7 2.2A3.5 3.5 0 0 0 14 1.1L1.7 13.4a1 1 0 0 0-.3.4l-1.3 5a.9.9 0 0 0 0 .5 1 1 0 0 0 1 .6l5-1.3c.2 0 .4-.1.5-.3L18.9 6a3.5 3.5 0 0 0 .7-3.8zm-6.8 2.6L15.2 7l-8.6 8.7-2.4-2.4zm-10.7 13l1-3.3L5.4 17zM18 4.2l-.4.5L16.3 6 14 3.7l1.3-1.3A1.7 1.7 0 0 1 18 3.6l-.1.6zM9 17.9h11v1H9v-1z\"><\/path>\n\n<\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"typeIt\">\n\t\t\t\t\t<a href=\"#\" class=\"\" title=\"Taper\" aria-label=\"Taper\">\n\t\t\t\t\t\t<svg  viewBox=\"0 0 22 20\" class=\"frmsvg\">\n\t<title>keyboard<\/title>\n\t<path d=\"M20.6 2.5H2c-1 0-1.9.8-1.9 1.9v11.2c0 1 .8 1.9 1.9 1.9h18.7c1 0 1.9-.8 1.9-1.9V4.4c0-1-.8-1.9-1.9-1.9zm.3 13.1c0 .2-.1.3-.3.3H2a.3.3 0 0 1-.3-.3V4.4c0-.2.1-.3.3-.3h18.7c.2 0 .3.1.3.3v11.2zm-14.3-5V9.4c0-.3-.2-.5-.4-.5H5c-.3 0-.5.2-.5.5v1c0 .3.2.5.5.5h1c.3 0 .5-.2.5-.5zm3.8 0V9.4c0-.3-.2-.5-.5-.5H9c-.3 0-.5.2-.5.5v1c0 .3.2.5.4.5H10c.3 0 .5-.2.5-.5zm3.7 0V9.4c0-.3-.2-.5-.4-.5h-1.1c-.3 0-.5.2-.5.5v1c0 .3.2.5.5.5h1c.3 0 .5-.2.5-.5zm3.8 0V9.4c0-.3-.2-.5-.5-.5h-1c-.3 0-.5.2-.5.5v1c0 .3.2.5.4.5h1.1c.3 0 .5-.2.5-.5zM4.8 7.2v-1c0-.3-.2-.5-.5-.5H3.2c-.3 0-.5.2-.5.4v1.1c0 .3.2.5.5.5h1.1c.3 0 .5-.2.5-.5zm3.7 0v-1c0-.3-.2-.5-.5-.5H7c-.3 0-.5.2-.5.4v1.1c0 .3.2.5.5.5h1c.3 0 .5-.2.5-.5zm3.8 0v-1c0-.3-.2-.5-.5-.5h-1.1c-.3 0-.5.2-.5.4v1.1c0 .3.2.5.5.5h1.1c.3 0 .5-.2.5-.5zm3.7 0v-1c0-.3-.2-.5-.5-.5h-1c-.3 0-.5.2-.5.4v1.1c0 .3.2.5.5.5h1c.3 0 .5-.2.5-.5zm3.8 0v-1c0-.3-.2-.5-.5-.5h-1.1c-.3 0-.5.2-.5.4v1.1c0 .3.2.5.5.5h1.1c.3 0 .5-.2.5-.5zm-2 6.2V13c0-.3-.2-.5-.6-.5h-12c-.3 0-.6.2-.6.5v.6c0 .3.3.5.7.5h12c.3 0 .6-.2.6-.5z\"><\/path>\n<\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t<\/ul>\n\n\t\t<span class=\"frm-typed-drawline\"><\/span>\n\n\t\t<div class=\"typed\">\n\t\t\t<input type=\"text\" name=\"item_meta[444][typed]\" class=\"name\" id=\"field_58ua8d04a8d538effbf780014\" autocomplete=\"off\" value=\"\"  style=\"width:400px\" maxlength=\"150\" data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" aria-required=\"true\" class=\"auto_width\" aria-invalid=\"false\"   \/>\n\t\t<\/div>\n\n\t\t<canvas class=\"pad\" data-fieldid=\"444\" data-fieldname=\"item_meta[444]\" width=\"396\" height=\"150\"><\/canvas>\n\t\t<div class=\"clearButton\"><a href=\"#clear\">D\u00e9gager<\/a><\/div>\n\n\t\t<input type=\"hidden\" name=\"item_meta[444][output]\" class=\"output\" value=\"\" \/>\n\t<\/div>\n<\/div>\n\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_445_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_42krkacd6f941c3\" id=\"field_42krkacd6f941c3_label\" class=\"frm_primary_label\">Date\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_42krkacd6f941c3\" name=\"item_meta[445]\" value=\"\"  maxlength=\"10\" data-reqmsg=\"Ce champ ne peut \u00eatre vide.\" aria-required=\"true\" data-invmsg=\"La date n&#039;est pas valide\" class=\"frm_date\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_446_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_iq5ko2000b179e8_label\" class=\"frm_primary_label\">reCAPTCHA\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_iq5ko2000b179e8\" class=\"frm-g-recaptcha\" data-sitekey=\"6Ldut1gbAAAAAITTpIrzZYdInS-7Sy7il0TzBrxc\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_474_container\" class=\"frm_form_field form-field \">\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">SUBMIT  \u2192<\/button>\r\n\r\n<\/div>\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_476_container\">\n\t\t\t<label for=\"field_tthmc\" >\n\t\t\t\tSi vous \u00eates un humain, ne remplissez pas ce champ.\t\t\t<\/label>\n\t\t\t<input  id=\"field_tthmc\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[476]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"zfQgj3u1deVobZvtzwhtNJKTjRpJbezEwJqjNIodrjatU8mvZtczkQSHn4Qh4mmQ\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_empty_space][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Les candidats qui ont \u00e9chou\u00e9 trois fois \u00e0 l&rsquo;\u00e9valuation des comp\u00e9tences cliniques (ECC) peuvent se r\u00e9inscrire au Processus d&rsquo;\u00e9quivalence. Pour se&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":917,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-5207","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/5207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=5207"}],"version-history":[{"count":11,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/5207\/revisions"}],"predecessor-version":[{"id":98627,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/5207\/revisions\/98627"}],"up":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/917"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=5207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}