{"id":1173,"date":"2021-03-15T18:41:27","date_gmt":"2021-03-15T18:41:27","guid":{"rendered":"https:\/\/ndeb.wpengine.com\/?page_id=1173"},"modified":"2022-07-07T14:42:22","modified_gmt":"2022-07-07T18:42:22","slug":"politique-de-protection","status":"publish","type":"page","link":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/politique-de-protection\/","title":{"rendered":"Politique de Protection"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1613677754598{padding-top: 90px !important;padding-bottom: 120px !important;}\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbcontainer-1180&Prime;][vc_column][vc_column_text css=\u00a0\u00bb.vc_custom_1619719935652{padding-bottom: 30px !important;}\u00a0\u00bb]Le Bureau National d&rsquo;Examen dentaire du Canada (BNED) s&rsquo;engage \u00e0 prot\u00e9ger les renseignements personnels des candidats, des participants de son personnel et des membres du public.<\/p>\n<p>Notre politique de Protection des renseignements personnels expose l&rsquo;ensemble des engagements que nous prenons et les principes que nous suivons lorsqu&rsquo;il s&rsquo;agit de renseignements personnels. Nous comprenons l&rsquo;importance de pr\u00e9server le caract\u00e8re priv\u00e9 des renseignements personnels et sommes engag\u00e9s \u00e0 recueillir et utiliser ces renseignements personnels de mani\u00e8re responsable, conform\u00e9ment aux lois canadiennes et provinciales sur la protection des renseignements personnels.<\/p>\n<h2 class=\"h3\">Renseignements personnels<\/h2>\n<p>Les renseignements personnels sont des renseignements sp\u00e9cifiques et identifiables s\u2019appliquant \u00e0 un individu. Pour les <strong>candidats<\/strong> et les <strong>participants<\/strong>, ces renseignements peuvent inclure, le nom de l&rsquo;individu, son adresse personnelle, son num\u00e9ro de t\u00e9l\u00e9phone, son num\u00e9ro de t\u00e9l\u00e9copieur, son adresse \u00e9lectronique, son sexe, sa photo et ses r\u00e9sultats acad\u00e9miques. Ces informations peuvent \u00eatre recueillies au moment de la soumission d\u2019inscription ou de profil via le site web <a href=\"https:\/\/ndeb.brighttrac.com\/\">https:\/\/ndeb.brighttrac.com<\/a> ou autrement.<\/p>\n<p>Pour les <strong>employ\u00e9s<\/strong> d&rsquo;autres renseignements personnels peuvent \u00eatre aussi recueillis.<\/p>\n<p>Pour les <strong>Visiteurs des sites web<\/strong> <a href=\"https:\/\/ndeb-bned.ca\/activity-log-backup\/\">www.ndeb-bned.ca<\/a> et <a href=\"https:\/\/ndeb.brighttrac.com\/\">https:\/\/ndeb.brighttrac.com<\/a> (Les \u00ab sites Web \u00bb), le serveur ne recueille et ne garde que les informations par d\u00e9faut couramment sauvegard\u00e9es par les logiciels de serveur web.\u00a0 Ces informations peuvent inclure la date et l\u2019heure de votre visite, l\u2019origine de l\u2019adresse IP et les pages et images demand\u00e9es.<\/p>\n<p>Veuillez noter que les <strong>enfants de moins de treize (13) ans<\/strong> ne doivent pas utiliser les sites web ou les services offerts sur les sites pour soumettre toute information personnelle les concernant.<\/p>\n<h3>Principes<\/h3>\n<p>Les principes suivants constituent la Politique du BNED touchant la Protection des renseignements personnels.<\/p>\n<ol>\n<li><strong>Obligation de rendre des comptes<\/strong> &#8211; Le BNED est responsable de tous les renseignements personnels qui sont sous son contr\u00f4le. Le responsable de la Protection des renseignements personnels, pour le BNED, doit s\u2019assurer que ses actions sont conformes \u00e0 la politique de Protection des renseignements personnels du BNED.<\/li>\n<li><strong>Identification du but de la collecte de l&rsquo;information<\/strong>\u2013 Les motifs de la collecte de renseignements personnels doivent \u00eatre pr\u00e9cis\u00e9s avant ou au moment de la collecte. Le BNED ne recueillera et ne conservera que les renseignements d\u00e9j\u00e0 d\u00e9termin\u00e9s et n\u00e9cessaires \u00e0 la r\u00e9alisation de son mandat, \u00e0 moins que des mesures diff\u00e9rentes ne soient exig\u00e9es ou pr\u00e9vues par la loi.<\/li>\n<li><strong>Consentement<\/strong> \u2013 Un consentement \u00e9clair\u00e9 est exig\u00e9 au moment ou avant le moment de la collecte, de l\u2019utilisation ou de la divulgation des renseignements personnels, \u00e0 moins que des mesures diff\u00e9rentes ne soient exig\u00e9es ou pr\u00e9vues par la loi.<\/li>\n<li><strong>Limitation de l&rsquo;utilisation, de la divulgation et de la conservation<\/strong>&#8211; Le BNED s\u2019engage \u00e0 n\u2019utiliser ou divulguer les renseignements personnels qu\u2019aux fins pour lesquelles ils ont \u00e9t\u00e9 recueillis. Les renseignements personnels sur les candidats, participants et d\u00e9tenteurs de certificat sont gard\u00e9s aussi longtemps que n\u00e9cessaire pour les fins d\u00e9termin\u00e9es par le mandat du Bureau et sont conserv\u00e9s \u00e0 long terme dans des fichiers s\u00e9curitaires. Les renseignements concernant les employ\u00e9s sont d\u00e9truits au bout de sept ans d&rsquo;inactivit\u00e9.<\/li>\n<li><strong>Exactitude de l&rsquo;information<\/strong>&#8211; Le BNED d\u00e9ploie tous les efforts pour s&rsquo;assurer que les renseignements personnels soient exacts, complets et \u00e0 jour.<\/li>\n<li><strong>Mesures de s\u00e9curit\u00e9 pour les renseignements personnels<\/strong>&#8211; Le BNED applique sans arr\u00eat les mesures n\u00e9cessaires \u00e0 assurer que tous les renseignements personnels enregistr\u00e9s soient prot\u00e9g\u00e9s contre toute consultation, divulgation ou utilisation non autoris\u00e9es.<\/li>\n<li><strong>Transparence<\/strong>&#8211; L&rsquo;information concernant les politiques et les pratiques relatives \u00e0 la gestion des renseignements personnels est disponible au bureau du BNED. Ces politiques et pratiques font r\u00e9f\u00e9rence \u00e0 la collecte, l\u2019utilisation et la divulgation des informations personnelles appartenant aux candidats et participants, aux membres du Bureau, examinateurs, consultants, employ\u00e9s et autres.\u00a0 Les demandes de renseignements sur la fa\u00e7on par laquelle le BNED g\u00e8re vos informations personnelles peuvent \u00eatre adress\u00e9es par \u00e9crit au responsable de la Protection des renseignements personnels \u00e0 l\u2019adresse ci-dessous.<\/li>\n<li><strong>Acc\u00e8s aux renseignements personnels<\/strong>&#8211; Sur demande \u00e9crite, et dans les 30 jours ouvrables, un individu a le droit de consulter ses renseignements personnels sous le contr\u00f4le du BNED, incluant la demande \u00e0 savoir si et comment ces informations ont \u00e9t\u00e9 utilis\u00e9es et \u00e0 quel tiers parti elles ont \u00e9t\u00e9 divulgu\u00e9es.\u00a0 Des demandes de mise \u00e0 jour ou de modification des renseignements personnels sous le contr\u00f4le du BNED doivent \u00eatre adress\u00e9es par \u00e9crit au responsable de la Protection des renseignements personnels, \u00e0 l\u2019adresse ci-dessous.\u00a0 Veuillez noter que les informations personnelles ne peuvent \u00eatre communiqu\u00e9es \u00e0 des tiers que si un consentement expr\u00e8s est fourni au BNED ou si requis par la loi.<\/li>\n<\/ol>\n<p><strong>Conformit\u00e9 et plaintes<\/strong>&#8211; Les plaintes, les pr\u00e9occupations, les demandes d&rsquo;acc\u00e8s et les demandes de modification des renseignements personnels ou des questions doivent \u00eatre adress\u00e9es par \u00e9crit au responsable de la Protection des renseignements personnels du BNED. Le responsable de la Protection des renseignements personnels fera enqu\u00eate sur toutes les plaintes pr\u00e9sent\u00e9es au bureau par \u00e9crit. Si la plainte est justifi\u00e9e, le responsable de la Protection des renseignements personnels prendra les mesures pour la corriger et, le cas \u00e9ch\u00e9ant, pour apporter les modifications n\u00e9cessaires aux politiques et aux proc\u00e9dures existantes touchant la Protection des renseignements personnels. Si la plainte ne peut \u00eatre r\u00e9solue \u00e0 votre satisfaction par le BNED, on vous renseignera et vous orientera vers l&rsquo;agence gouvernementale appropri\u00e9e apte \u00e0 vous procurer plus d&rsquo;informations.[\/vc_column_text][vc_column_text css=\u00a0\u00bb.vc_custom_1657219336278{padding-bottom: 30px !important;}\u00a0\u00bb]<\/p>\n<h3>Coordonn\u00e9es<\/h3>\n<p>Responsable de la Protection des renseignements personnels<\/p>\n<p>Bureau national d&rsquo;examen dentaire du Canada<br \/>\n340, rue Albert, 12e \u00e9tage<br \/>\nOttawa, Ontario K1R 7Y6<\/p>\n<p>T\u00e9l\u00e9phone: 613 236-5912<br \/>\nT\u00e9l\u00e9copieur: 613-236-8386<\/p>\n<p>Courriel: <a href=\"mailto:info@ndeb-bned.ca\">info@ndeb-bned.ca<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1613677754598{padding-top: 90px !important;padding-bottom: 120px !important;}\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbcontainer-1180&Prime;][vc_column][vc_column_text css=\u00a0\u00bb.vc_custom_1619719935652{padding-bottom: 30px !important;}\u00a0\u00bb]Le Bureau National d&rsquo;Examen dentaire du Canada (BNED) s&rsquo;engage \u00e0 prot\u00e9ger les renseignements&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"full_width.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1173","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":1,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/1173\/revisions"}],"predecessor-version":[{"id":78231,"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/pages\/1173\/revisions\/78231"}],"wp:attachment":[{"href":"https:\/\/ndeb-bned.ca\/activity-log-backup\/fr\/wp-json\/wp\/v2\/media?parent=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}